{"id":281,"date":"2018-11-07T08:30:41","date_gmt":"2018-11-07T12:30:41","guid":{"rendered":"http:\/\/192.168.1.138\/wordpress\/?page_id=281"},"modified":"2022-03-25T16:01:01","modified_gmt":"2022-03-25T20:01:01","slug":"mapadelsitio","status":"publish","type":"page","link":"https:\/\/www.arssenasa.gob.do\/index.php\/mapadelsitio\/","title":{"rendered":"Mapa del Sitio"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"281\" class=\"elementor elementor-281\" data-elementor-settings=\"{&quot;ha_cmc_init_switcher&quot;:&quot;no&quot;}\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f065275 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f065275\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-350017d\" data-id=\"350017d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2b6df83 elementor-widget elementor-widget-template\" data-id=\"2b6df83\" data-element_type=\"widget\" data-widget_type=\"template.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-template\">\n\t\t\t\t\t<header data-elementor-type=\"header\" data-elementor-id=\"7953\" class=\"elementor elementor-7953\" data-elementor-settings=\"{&quot;ha_cmc_init_switcher&quot;:&quot;no&quot;}\" data-elementor-post-type=\"elementor_library\">\n\t\t\t<div class=\"elementor-element elementor-element-2b96271 e-flex e-con-boxed e-con e-parent\" data-id=\"2b96271\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-83d270e elementor-widget elementor-widget-breadcrumbs\" data-id=\"83d270e\" data-element_type=\"widget\" data-widget_type=\"breadcrumbs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p id=\"breadcrumbs\"><span><span><a href=\"https:\/\/www.arssenasa.gob.do\/\">Inicio<\/a><\/span><\/span><\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/header>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5356815 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5356815\" data-element_type=\"section\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-24272ab\" data-id=\"24272ab\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-db7d737 elementor-widget elementor-widget-template\" data-id=\"db7d737\" data-element_type=\"widget\" data-widget_type=\"template.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-template\">\n\t\t\t\t\t<div data-elementor-type=\"section\" data-elementor-id=\"10923\" class=\"elementor elementor-10923\" data-elementor-settings=\"{&quot;ha_cmc_init_switcher&quot;:&quot;no&quot;}\" data-elementor-post-type=\"elementor_library\">\n\t\t\t<div class=\"elementor-element elementor-element-be1769a e-flex e-con-boxed e-con e-parent\" data-id=\"be1769a\" data-element_type=\"container\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-b715723 e-con-full e-flex e-con e-child\" data-id=\"b715723\" data-element_type=\"container\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0a304c6 elementor-share-buttons--view-icon elementor-share-buttons--skin-minimal elementor-share-buttons--shape-circle elementor-share-buttons--color-custom elementor-grid-0 elementor-widget elementor-widget-share-buttons\" data-id=\"0a304c6\" data-element_type=\"widget\" data-widget_type=\"share-buttons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-grid\" role=\"list\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t\t<div class=\"elementor-share-btn elementor-share-btn_print\" role=\"button\" tabindex=\"0\" aria-label=\"Share on print\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__icon\">\n\t\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-print\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M448 192V77.25c0-8.49-3.37-16.62-9.37-22.63L393.37 9.37c-6-6-14.14-9.37-22.63-9.37H96C78.33 0 64 14.33 64 32v160c-35.35 0-64 28.65-64 64v112c0 8.84 7.16 16 16 16h48v96c0 17.67 14.33 32 32 32h320c17.67 0 32-14.33 32-32v-96h48c8.84 0 16-7.16 16-16V256c0-35.35-28.65-64-64-64zm-64 256H128v-96h256v96zm0-224H128V64h192v48c0 8.84 7.16 16 16 16h48v96zm48 72c-13.25 0-24-10.75-24-24 0-13.26 10.75-24 24-24s24 10.74 24 24c0 13.25-10.75 24-24 24z\"><\/path><\/svg>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t\t<div class=\"elementor-share-btn elementor-share-btn_email\" role=\"button\" tabindex=\"0\" aria-label=\"Share on email\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__icon\">\n\t\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-envelope\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M502.3 190.8c3.9-3.1 9.7-.2 9.7 4.7V400c0 26.5-21.5 48-48 48H48c-26.5 0-48-21.5-48-48V195.6c0-5 5.7-7.8 9.7-4.7 22.4 17.4 52.1 39.5 154.1 113.6 21.1 15.4 56.7 47.8 92.2 47.6 35.7.3 72-32.8 92.3-47.6 102-74.1 131.6-96.3 154-113.7zM256 320c23.2.4 56.6-29.2 73.4-41.4 132.7-96.3 142.8-104.7 173.4-128.7 5.8-4.5 9.2-11.5 9.2-18.9v-19c0-26.5-21.5-48-48-48H48C21.5 64 0 85.5 0 112v19c0 7.4 3.4 14.3 9.2 18.9 30.6 23.9 40.7 32.4 173.4 128.7 16.8 12.2 50.2 41.8 73.4 41.4z\"><\/path><\/svg>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c78a91d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c78a91d\" data-element_type=\"section\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1ca2de4\" data-id=\"1ca2de4\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5e2b947 elementor-widget elementor-widget-sitemap\" data-id=\"5e2b947\" data-element_type=\"widget\" data-widget_type=\"sitemap.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-sitemap-wrap\"><div class=\"elementor-sitemap-section\"><h2 class=\"elementor-sitemap-title elementor-sitemap-page-title\">P\u00e1ginas<\/h2><ul class=\"elementor-sitemap-list elementor-sitemap-page-list\"><li class=\"elementor-sitemap-item elementor-sitemap-item-page page_item page-item-1547\"><a href=\"https:\/\/www.arssenasa.gob.do\/index.php\/politicasdeprivacidad\/\">Pol\u00edticas de Privacidad<\/a><\/li><li class=\"elementor-sitemap-item elementor-sitemap-item-page page_item page-item-780\"><a href=\"https:\/\/www.arssenasa.gob.do\/index.php\/regimen-contributivo\/\">R\u00e9gimen Contributivo<\/a><\/li><li class=\"elementor-sitemap-item elementor-sitemap-item-page page_item page-item-270\"><a href=\"https:\/\/www.arssenasa.gob.do\/index.php\/noticias\/\">Noticias<\/a><\/li><li class=\"elementor-sitemap-item elementor-sitemap-item-page page_item page-item-17167\"><a href=\"https:\/\/www.arssenasa.gob.do\/index.php\/club-de-beneficios\/\">Club de Beneficios<\/a><\/li><li class=\"elementor-sitemap-item elementor-sitemap-item-page page_item page-item-22031\"><a href=\"https:\/\/www.arssenasa.gob.do\/index.php\/vias-de-denuncias\/\">V\u00edas de Denuncias<\/a><\/li><li class=\"elementor-sitemap-item elementor-sitemap-item-page page_item page-item-1553\"><a href=\"https:\/\/www.arssenasa.gob.do\/index.php\/terminosdeuso\/\">T\u00e9rminos de Uso<\/a><\/li><li class=\"elementor-sitemap-item elementor-sitemap-item-page page_item page-item-281\"><a href=\"https:\/\/www.arssenasa.gob.do\/index.php\/mapadelsitio\/\">Mapa del Sitio<\/a><\/li><li class=\"elementor-sitemap-item elementor-sitemap-item-page page_item page-item-1564\"><a href=\"https:\/\/www.arssenasa.gob.do\/index.php\/appsenasa\/\">App SeNaSa<\/a><\/li><li class=\"elementor-sitemap-item elementor-sitemap-item-page page_item page-item-11553\"><a href=\"https:\/\/www.arssenasa.gob.do\/index.php\/servicios\/\">Servicios<\/a><ul class='children'><li class=\"elementor-sitemap-item elementor-sitemap-item-page page_item page-item-2324\"><a href=\"https:\/\/www.arssenasa.gob.do\/index.php\/servicios\/servicios-pensionados-jubilados\/\">Servicios Pensionados y Jubilados<\/a><ul class='children'><li class=\"elementor-sitemap-item elementor-sitemap-item-page page_item page-item-16642\"><a href=\"https:\/\/www.arssenasa.gob.do\/index.php\/servicios\/servicios-pensionados-jubilados\/solicitud-de-reembolso-de-servicios-de-salud\/\">Solicitud de Reembolso de Servicios de Salud<\/a><\/li><li class=\"elementor-sitemap-item elementor-sitemap-item-page page_item page-item-8974\"><a href=\"https:\/\/www.arssenasa.gob.do\/index.php\/servicios\/servicios-pensionados-jubilados\/solicitud-de-autorizacion\/\">Solicitud de Autorizaci\u00f3n<\/a><\/li><li class=\"elementor-sitemap-item elementor-sitemap-item-page page_item page-item-16436\"><a href=\"https:\/\/www.arssenasa.gob.do\/index.php\/servicios\/servicios-pensionados-jubilados\/afiliacion-dependientes-adicionales-pensionados-y-jubilados\/\">Afiliaci\u00f3n Dependientes Adicionales (Pensionados y Jubilados)<\/a><\/li><li class=\"elementor-sitemap-item elementor-sitemap-item-page page_item page-item-3471\"><a href=\"https:\/\/www.arssenasa.gob.do\/index.php\/servicios\/servicios-pensionados-jubilados\/duplicado-de-carnet-pensionados-y-jubilados\/\">Impresi\u00f3n de Carn\u00e9 Pensionados y Jubilados<\/a><\/li><li class=\"elementor-sitemap-item elementor-sitemap-item-page page_item page-item-3477\"><a href=\"https:\/\/www.arssenasa.gob.do\/index.php\/servicios\/servicios-pensionados-jubilados\/solicitud-de-afiliacion-para-plan-de-pensionados\/\">Solicitud de Afiliaci\u00f3n titular Pensionados y\/o Jubilados<\/a><\/li><li class=\"elementor-sitemap-item elementor-sitemap-item-page page_item page-item-3481\"><a href=\"https:\/\/www.arssenasa.gob.do\/index.php\/servicios\/servicios-pensionados-jubilados\/pre-autorizacion-de-servicios-de-alto-costo-sin-materiales\/\">Preautorizaci\u00f3n de Servicios de Alto Costo sin Materiales<\/a><\/li><li class=\"elementor-sitemap-item elementor-sitemap-item-page page_item page-item-3485\"><a href=\"https:\/\/www.arssenasa.gob.do\/index.php\/servicios\/servicios-pensionados-jubilados\/afiliacion-dependientes-directos-esposos-e-hijos-menores\/\">Afiliaci\u00f3n Dependientes Directos (esposos e hijos o hijastros menores)<\/a><\/li><li class=\"elementor-sitemap-item elementor-sitemap-item-page page_item page-item-16544\"><a href=\"https:\/\/www.arssenasa.gob.do\/index.php\/servicios\/servicios-pensionados-jubilados\/afiliacion-hijos-con-discapacidad\/\">Afiliaci\u00f3n Hijos con Discapacidad<\/a><\/li><li class=\"elementor-sitemap-item elementor-sitemap-item-page page_item page-item-3489\"><a href=\"https:\/\/www.arssenasa.gob.do\/index.php\/servicios\/servicios-pensionados-jubilados\/pre-autorizacion-de-servicios-medicos-electivos\/\">Preautorizaci\u00f3n de Servicios de Salud<\/a><\/li><li class=\"elementor-sitemap-item elementor-sitemap-item-page page_item page-item-3493\"><a href=\"https:\/\/www.arssenasa.gob.do\/index.php\/servicios\/servicios-pensionados-jubilados\/pre-autorizacion-de-terapias-fisicas\/\">Preautorizaci\u00f3n de Ter\u00e1pias F\u00edsicas<\/a><\/li><li class=\"elementor-sitemap-item elementor-sitemap-item-page page_item page-item-16568\"><a href=\"https:\/\/www.arssenasa.gob.do\/index.php\/servicios\/servicios-pensionados-jubilados\/solicitud-de-afiliacion-dependientes-hijos-o-hijastros-con-edades-entre-18-y-21-anos\/\">Afiliaci\u00f3n Dependientes Hijos o Hijastros con edades entre 18 y 21 a\u00f1os<\/a><\/li><\/ul><\/li><li class=\"elementor-sitemap-item elementor-sitemap-item-page page_item page-item-578\"><a href=\"https:\/\/www.arssenasa.gob.do\/index.php\/servicios\/servicios-regimen-subsidiado-2\/\">Servicios R\u00e9gimen Subsidiado<\/a><ul class='children'><li class=\"elementor-sitemap-item elementor-sitemap-item-page page_item page-item-4261\"><a href=\"https:\/\/www.arssenasa.gob.do\/index.php\/servicios\/servicios-regimen-subsidiado-2\/imprimir-carta-de-afiliacion\/\">Impresi\u00f3n Carta de Afiliaci\u00f3n<\/a><\/li><li class=\"elementor-sitemap-item elementor-sitemap-item-page page_item page-item-3515\"><a href=\"https:\/\/www.arssenasa.gob.do\/index.php\/servicios\/servicios-regimen-subsidiado-2\/duplicado-de-carnet-regimen-subsidiado\/\">Impresi\u00f3n de Carn\u00e9 R\u00e9gimen Subsidiado<\/a><\/li><li class=\"elementor-sitemap-item elementor-sitemap-item-page page_item page-item-3522\"><a href=\"https:\/\/www.arssenasa.gob.do\/index.php\/servicios\/servicios-regimen-subsidiado-2\/solicitud-de-afiliacion-titular-al-regimen-subsidiado\/\">Solicitud de Afiliaci\u00f3n Titular al R\u00e9gimen Subsidiado<\/a><\/li><li class=\"elementor-sitemap-item elementor-sitemap-item-page page_item page-item-3526\"><a href=\"https:\/\/www.arssenasa.gob.do\/index.php\/servicios\/servicios-regimen-subsidiado-2\/pre-autorizacion-de-servicios-de-alto-costo-sin-materiales\/\">Preautorizaci\u00f3n de Servicios de Salud<\/a><\/li><li class=\"elementor-sitemap-item elementor-sitemap-item-page page_item page-item-3530\"><a href=\"https:\/\/www.arssenasa.gob.do\/index.php\/servicios\/servicios-regimen-subsidiado-2\/afiliacion-dependientes-directos-esposos-e-hijos-menores\/\">Afiliaci\u00f3n Dependientes Directos (esposos e hijos o hijastros menores)<\/a><\/li><li class=\"elementor-sitemap-item elementor-sitemap-item-page page_item page-item-3534\"><a href=\"https:\/\/www.arssenasa.gob.do\/index.php\/servicios\/servicios-regimen-subsidiado-2\/afiliacion-hijos-adoptivos\/\">Afiliaci\u00f3n Hijos Adoptivos<\/a><\/li><li class=\"elementor-sitemap-item elementor-sitemap-item-page page_item page-item-3538\"><a href=\"https:\/\/www.arssenasa.gob.do\/index.php\/servicios\/servicios-regimen-subsidiado-2\/afiliacion-hijos-con-discapacidad\/\">Afiliaci\u00f3n Hijos con Discapacidad<\/a><\/li><li class=\"elementor-sitemap-item elementor-sitemap-item-page page_item page-item-3542\"><a href=\"https:\/\/www.arssenasa.gob.do\/index.php\/servicios\/servicios-regimen-subsidiado-2\/afiliacion-dependiente-alcanza-mayoria-de-edad\/\">Afiliaci\u00f3n Dependiente Alcanza Mayor\u00eda de Edad<\/a><\/li><li class=\"elementor-sitemap-item elementor-sitemap-item-page page_item page-item-3550\"><a href=\"https:\/\/www.arssenasa.gob.do\/index.php\/servicios\/servicios-regimen-subsidiado-2\/cambio-de-titularidad-por-fallecimiento\/\">Cambio de titularidad por fallecimiento<\/a><\/li><li class=\"elementor-sitemap-item elementor-sitemap-item-page page_item page-item-16623\"><a href=\"https:\/\/www.arssenasa.gob.do\/index.php\/servicios\/servicios-regimen-subsidiado-2\/solicitud-de-reembolso-de-servicios-de-salud\/\">Solicitud de Reembolso de Servicios de Salud<\/a><\/li><\/ul><\/li><li class=\"elementor-sitemap-item elementor-sitemap-item-page page_item page-item-4709\"><a href=\"https:\/\/www.arssenasa.gob.do\/index.php\/servicios\/servicios-senasa-larimar\/\">Servicios SeNaSa Larimar<\/a><ul class='children'><li class=\"elementor-sitemap-item elementor-sitemap-item-page page_item page-item-4712\"><a href=\"https:\/\/www.arssenasa.gob.do\/index.php\/servicios\/servicios-senasa-larimar\/duplicado-de-carnet-senasa-larimar\/\">Impresi\u00f3n de carn\u00e9 SeNaSa Larimar<\/a><\/li><li class=\"elementor-sitemap-item elementor-sitemap-item-page page_item page-item-4736\"><a href=\"https:\/\/www.arssenasa.gob.do\/index.php\/servicios\/servicios-senasa-larimar\/afiliacion-de-dependientes-directos-esposo-a-e-hijos-menores-senasa-larimar\/\">Afiliaci\u00f3n de dependientes directos (esposo\/a e hijos o hijastros menores) SeNaSa Larimar<\/a><\/li><li class=\"elementor-sitemap-item elementor-sitemap-item-page page_item page-item-4744\"><a href=\"https:\/\/www.arssenasa.gob.do\/index.php\/servicios\/servicios-senasa-larimar\/pre-autorizacion-de-servicios-de-salud\/\">Preautorizaci\u00f3n de Servicios de Salud<\/a><\/li><li class=\"elementor-sitemap-item elementor-sitemap-item-page page_item page-item-4751\"><a href=\"https:\/\/www.arssenasa.gob.do\/index.php\/servicios\/servicios-senasa-larimar\/pre-autorizacion-de-terapias-fisicas\/\">Preautorizaci\u00f3n de Terapias F\u00edsicas<\/a><\/li><li class=\"elementor-sitemap-item elementor-sitemap-item-page page_item page-item-4761\"><a href=\"https:\/\/www.arssenasa.gob.do\/index.php\/servicios\/servicios-senasa-larimar\/solicitud-de-reactivacion-de-autorizacion\/\">Solicitud de Reactivaci\u00f3n de autorizaci\u00f3n<\/a><\/li><li class=\"elementor-sitemap-item elementor-sitemap-item-page page_item page-item-4772\"><a href=\"https:\/\/www.arssenasa.gob.do\/index.php\/servicios\/servicios-senasa-larimar\/solicitud-de-plan-voluntario-senasa-larimar\/\">Solicitud de afiliaci\u00f3n titular Plan Voluntario SeNaSa Larimar<\/a><\/li><\/ul><\/li><li class=\"elementor-sitemap-item elementor-sitemap-item-page page_item page-item-2436\"><a href=\"https:\/\/www.arssenasa.gob.do\/index.php\/servicios\/servicios-prestadores-servicio\/\">Servicios para Prestadores<\/a><ul class='children'><li class=\"elementor-sitemap-item elementor-sitemap-item-page page_item page-item-3396\"><a href=\"https:\/\/www.arssenasa.gob.do\/index.php\/servicios\/servicios-prestadores-servicio\/entrega-de-carta-de-retencion-de-impuestos\/\">Entrega de Carta de Retenci\u00f3n de Impuestos<\/a><\/li><li class=\"elementor-sitemap-item elementor-sitemap-item-page page_item page-item-21581\"><a href=\"https:\/\/www.arssenasa.gob.do\/index.php\/servicios\/servicios-prestadores-servicio\/preguntas-frecuentes\/\">Preguntas Frecuentes<\/a><\/li><li class=\"elementor-sitemap-item elementor-sitemap-item-page page_item page-item-3412\"><a href=\"https:\/\/www.arssenasa.gob.do\/index.php\/servicios\/servicios-prestadores-servicio\/solicitud-de-entrega-de-tarifario-a-pss\/\">Solicitud de Entrega de Tarifario a PSS<\/a><\/li><li class=\"elementor-sitemap-item elementor-sitemap-item-page page_item page-item-3423\"><a href=\"https:\/\/www.arssenasa.gob.do\/index.php\/servicios\/servicios-prestadores-servicio\/solicitud-de-afiliacion-pss\/\">Solicitud de Afiliaci\u00f3n y Contrataci\u00f3n de Nuevos Servicios PSS<\/a><\/li><li class=\"elementor-sitemap-item elementor-sitemap-item-page page_item page-item-3431\"><a href=\"https:\/\/www.arssenasa.gob.do\/index.php\/servicios\/servicios-prestadores-servicio\/solicitud-de-usuario-web\/\">Solicitud de Usuario Web<\/a><\/li><li class=\"elementor-sitemap-item elementor-sitemap-item-page page_item page-item-3435\"><a href=\"https:\/\/www.arssenasa.gob.do\/index.php\/servicios\/servicios-prestadores-servicio\/contratacion-de-nuevo-servicio\/\">Contrataci\u00f3n de nuevo servicio<\/a><\/li><li class=\"elementor-sitemap-item elementor-sitemap-item-page page_item page-item-3442\"><a href=\"https:\/\/www.arssenasa.gob.do\/index.php\/servicios\/servicios-prestadores-servicio\/solicitud-de-pago-por-transferencia-bancaria\/\">Solicitud de Pago por Transferencia Bancaria<\/a><\/li><li class=\"elementor-sitemap-item elementor-sitemap-item-page page_item page-item-3447\"><a href=\"https:\/\/www.arssenasa.gob.do\/index.php\/servicios\/servicios-prestadores-servicio\/solicitud-de-acompanamiento-pss\/\">Solicitud de Acompa\u00f1amiento PSS<\/a><\/li><li class=\"elementor-sitemap-item elementor-sitemap-item-page page_item page-item-3451\"><a href=\"https:\/\/www.arssenasa.gob.do\/index.php\/servicios\/servicios-prestadores-servicio\/solicitud-de-reactivacion-de-codigo\/\">Solicitud de Reactivaci\u00f3n de C\u00f3digo<\/a><\/li><li class=\"elementor-sitemap-item elementor-sitemap-item-page page_item page-item-3455\"><a href=\"https:\/\/www.arssenasa.gob.do\/index.php\/servicios\/servicios-prestadores-servicio\/solicitud-de-pss-para-auditoria-de-expediente\/\">Solicitud de PSS para auditor\u00eda de Expediente<\/a><\/li><\/ul><\/li><li class=\"elementor-sitemap-item elementor-sitemap-item-page page_item page-item-457\"><a href=\"https:\/\/www.arssenasa.gob.do\/index.php\/servicios\/servicios-regimen-contributivo\/\">Servicios R\u00e9gimen Contributivo<\/a><ul class='children'><li class=\"elementor-sitemap-item elementor-sitemap-item-page page_item page-item-3587\"><a href=\"https:\/\/www.arssenasa.gob.do\/index.php\/servicios\/servicios-regimen-contributivo\/afiliacion-dependientes-directos-esposos-e-hijos-menores\/\">Afiliaci\u00f3n Dependientes Directos (esposos e hijos o hijastros menores)<\/a><\/li><li class=\"elementor-sitemap-item elementor-sitemap-item-page page_item page-item-3591\"><a href=\"https:\/\/www.arssenasa.gob.do\/index.php\/servicios\/servicios-regimen-contributivo\/afiliacion-hijos-nacidos-extranjeros\/\">Afiliaci\u00f3n Hijos Nacidos en el Extranjero<\/a><\/li><li class=\"elementor-sitemap-item elementor-sitemap-item-page page_item page-item-3600\"><a href=\"https:\/\/www.arssenasa.gob.do\/index.php\/servicios\/servicios-regimen-contributivo\/afiliacion-hijos-con-discapacidad\/\">Afiliaci\u00f3n Hijos con Discapacidad<\/a><\/li><li class=\"elementor-sitemap-item elementor-sitemap-item-page page_item page-item-8979\"><a href=\"https:\/\/www.arssenasa.gob.do\/index.php\/servicios\/servicios-regimen-contributivo\/solicitud-de-autorizacion\/\">Solicitud de Autorizaci\u00f3n<\/a><\/li><li class=\"elementor-sitemap-item elementor-sitemap-item-page page_item page-item-3604\"><a href=\"https:\/\/www.arssenasa.gob.do\/index.php\/servicios\/servicios-regimen-contributivo\/afiliacion-dependientes-adicionales\/\">Afiliaci\u00f3n Dependientes Adicionales<\/a><\/li><li class=\"elementor-sitemap-item elementor-sitemap-item-page page_item page-item-3608\"><a href=\"https:\/\/www.arssenasa.gob.do\/index.php\/servicios\/servicios-regimen-contributivo\/pre-autorizacion-de-servicios-medicos-electivos\/\">Preautorizaci\u00f3n de Servicios M\u00e9dicos Electivos<\/a><\/li><li class=\"elementor-sitemap-item elementor-sitemap-item-page page_item page-item-3609\"><a href=\"https:\/\/www.arssenasa.gob.do\/index.php\/servicios\/servicios-regimen-contributivo\/afiliacion-dependiente-alcanza-mayoria-de-edad\/\">Afiliaci\u00f3n Dependientes Hijos o Hijastros con edades entre 18 y 21 a\u00f1os<\/a><\/li><li class=\"elementor-sitemap-item elementor-sitemap-item-page page_item page-item-3616\"><a href=\"https:\/\/www.arssenasa.gob.do\/index.php\/servicios\/servicios-regimen-contributivo\/pre-autorizacion-de-terapias-fisicas\/\">Preautorizaci\u00f3n de Terapias F\u00edsicas<\/a><\/li><li class=\"elementor-sitemap-item elementor-sitemap-item-page page_item page-item-3633\"><a href=\"https:\/\/www.arssenasa.gob.do\/index.php\/servicios\/servicios-regimen-contributivo\/solicitud-de-planes-complementarios\/\">Solicitud de Planes Complementarios<\/a><\/li><li class=\"elementor-sitemap-item elementor-sitemap-item-page page_item page-item-16613\"><a href=\"https:\/\/www.arssenasa.gob.do\/index.php\/servicios\/servicios-regimen-contributivo\/solicitud-de-reembolso-servicios-salud\/\">Solicitud de Reembolso de Servicios de Salud<\/a><\/li><li class=\"elementor-sitemap-item elementor-sitemap-item-page page_item page-item-3564\"><a href=\"https:\/\/www.arssenasa.gob.do\/index.php\/servicios\/servicios-regimen-contributivo\/duplicado-de-carnet\/\">Impresi\u00f3n de Carn\u00e9<\/a><\/li><li class=\"elementor-sitemap-item elementor-sitemap-item-page page_item page-item-3570\"><a href=\"https:\/\/www.arssenasa.gob.do\/index.php\/servicios\/servicios-regimen-contributivo\/cambio-de-regimen-contributivo-al-regimen-subsidiado\/\">Cambio de R\u00e9gimen Contributivo al R\u00e9gimen Subsidiado<\/a><\/li><li class=\"elementor-sitemap-item elementor-sitemap-item-page page_item page-item-3574\"><a href=\"https:\/\/www.arssenasa.gob.do\/index.php\/servicios\/servicios-regimen-contributivo\/afiliacion-primer-empleo\/\">Afiliaci\u00f3n Primer Empleo<\/a><\/li><li class=\"elementor-sitemap-item elementor-sitemap-item-page page_item page-item-22518\"><a href=\"https:\/\/www.arssenasa.gob.do\/index.php\/servicios\/servicios-regimen-contributivo\/impresion-de-carne-cloned-3564\/\">Impresi\u00f3n de Carn\u00e9 &#8211; [Cloned #3564]<\/a><\/li><li class=\"elementor-sitemap-item elementor-sitemap-item-page page_item page-item-3579\"><a href=\"https:\/\/www.arssenasa.gob.do\/index.php\/servicios\/servicios-regimen-contributivo\/traspaso-a-senasa\/\">Traspaso a SeNaSa<\/a><\/li><li class=\"elementor-sitemap-item elementor-sitemap-item-page page_item page-item-3583\"><a href=\"https:\/\/www.arssenasa.gob.do\/index.php\/servicios\/servicios-regimen-contributivo\/pre-autorizacion-de-servicios-de-alto-costo-sin-materiales\/\">Preautorizaci\u00f3n de Servicios de Salud<\/a><\/li><\/ul><\/li><\/ul><\/li><li class=\"elementor-sitemap-item elementor-sitemap-item-page page_item page-item-22051\"><a href=\"https:\/\/www.arssenasa.gob.do\/index.php\/formulario-vias-de-denuncias\/\">Formulario V\u00edas de Denuncias<\/a><\/li><li class=\"elementor-sitemap-item elementor-sitemap-item-page page_item page-item-13867\"><a href=\"https:\/\/www.arssenasa.gob.do\/index.php\/denuncias-soborno\/\">Formulario para Denuncias de Soborno y Cumplimiento Regulatorio<\/a><\/li><li class=\"elementor-sitemap-item elementor-sitemap-item-page page_item page-item-16182\"><a href=\"https:\/\/www.arssenasa.gob.do\/index.php\/formulario-de-denuncias-y-sobornos\/\">Formulario de Denuncias y Sobornos<\/a><\/li><li class=\"elementor-sitemap-item elementor-sitemap-item-page page_item page-item-18752\"><a href=\"https:\/\/www.arssenasa.gob.do\/index.php\/jovenes-con-senasa\/\">J\u00f3venes con SeNaSa<\/a><\/li><li class=\"elementor-sitemap-item elementor-sitemap-item-page page_item page-item-66\"><a href=\"https:\/\/www.arssenasa.gob.do\/index.php\/quienes-somos\/\">\u00bfQui\u00e9nes somos?<\/a><ul class='children'><li class=\"elementor-sitemap-item elementor-sitemap-item-page page_item page-item-13069\"><a href=\"https:\/\/www.arssenasa.gob.do\/index.php\/quienes-somos\/estadisticas\/\">Estad\u00edsticas<\/a><\/li><li class=\"elementor-sitemap-item elementor-sitemap-item-page page_item page-item-22339\"><a href=\"https:\/\/www.arssenasa.gob.do\/index.php\/quienes-somos\/centros-y-puntos-de-servicio-proposal\/\">Centros y Puntos de Servicio &#8211; Proposal<\/a><\/li><li class=\"elementor-sitemap-item elementor-sitemap-item-page page_item page-item-3680\"><a href=\"https:\/\/www.arssenasa.gob.do\/index.php\/quienes-somos\/rsi\/\">Responsabilidad Social Institucional<\/a><ul class='children'><li class=\"elementor-sitemap-item elementor-sitemap-item-page page_item page-item-3936\"><a href=\"https:\/\/www.arssenasa.gob.do\/index.php\/quienes-somos\/rsi\/rsi-medio-ambiente\/\">Medio Ambiente<\/a><\/li><li class=\"elementor-sitemap-item elementor-sitemap-item-page page_item page-item-3942\"><a href=\"https:\/\/www.arssenasa.gob.do\/index.php\/quienes-somos\/rsi\/rsi-vida-sana\/\">Vida Sana<\/a><\/li><li class=\"elementor-sitemap-item elementor-sitemap-item-page page_item page-item-3947\"><a href=\"https:\/\/www.arssenasa.gob.do\/index.php\/quienes-somos\/rsi\/rsi-inclusion-social\/\">Inclusi\u00f3n Social<\/a><\/li><li class=\"elementor-sitemap-item elementor-sitemap-item-page page_item page-item-21379\"><a href=\"https:\/\/www.arssenasa.gob.do\/index.php\/quienes-somos\/rsi\/semana-de-la-sostenibilidad\/\">Semana de la Sostenibilidad<\/a><\/li><li class=\"elementor-sitemap-item elementor-sitemap-item-page page_item page-item-4842\"><a href=\"https:\/\/www.arssenasa.gob.do\/index.php\/quienes-somos\/rsi\/educacion-2\/\">Educaci\u00f3n<\/a><\/li><\/ul><\/li><li class=\"elementor-sitemap-item elementor-sitemap-item-page page_item page-item-14185\"><a href=\"https:\/\/www.arssenasa.gob.do\/index.php\/quienes-somos\/acuerdos-institucionales\/\">Acuerdos Institucionales<\/a><\/li><li class=\"elementor-sitemap-item elementor-sitemap-item-page page_item page-item-21363\"><a href=\"https:\/\/www.arssenasa.gob.do\/index.php\/quienes-somos\/canales-de-denuncia\/\">Canales de Denuncia<\/a><\/li><li class=\"elementor-sitemap-item elementor-sitemap-item-page page_item page-item-131\"><a href=\"https:\/\/www.arssenasa.gob.do\/index.php\/quienes-somos\/historia\/\">Historia<\/a><\/li><li class=\"elementor-sitemap-item elementor-sitemap-item-page page_item page-item-154\"><a href=\"https:\/\/www.arssenasa.gob.do\/index.php\/quienes-somos\/certificaciones-y-reconocimientos\/\">Certificaciones y Reconocimientos<\/a><\/li><li class=\"elementor-sitemap-item elementor-sitemap-item-page page_item page-item-160\"><a href=\"https:\/\/www.arssenasa.gob.do\/index.php\/quienes-somos\/director-ejecutivo\/\">Director Ejecutivo<\/a><\/li><li class=\"elementor-sitemap-item elementor-sitemap-item-page page_item page-item-169\"><a href=\"https:\/\/www.arssenasa.gob.do\/index.php\/quienes-somos\/marco-legal\/\">Marco Legal<\/a><\/li><li class=\"elementor-sitemap-item elementor-sitemap-item-page page_item page-item-21944\"><a href=\"https:\/\/www.arssenasa.gob.do\/index.php\/quienes-somos\/centros-y-puntos-de-servicio\/\">Centros y Puntos de Servicio<\/a><\/li><li class=\"elementor-sitemap-item elementor-sitemap-item-page page_item page-item-244\"><a href=\"https:\/\/www.arssenasa.gob.do\/index.php\/quienes-somos\/estudios-encuestas\/\">Estudios y Encuestas<\/a><\/li><\/ul><\/li><li class=\"elementor-sitemap-item elementor-sitemap-item-page page_item page-item-14403\"><a href=\"https:\/\/www.arssenasa.gob.do\/index.php\/senasaexterior\/\">SeNaSa Exterior<\/a><\/li><li class=\"elementor-sitemap-item elementor-sitemap-item-page page_item page-item-18499\"><a href=\"https:\/\/www.arssenasa.gob.do\/index.php\/guia-autorizaciones-medicas\/\">Gu\u00eda Autorizaciones M\u00e9dicas<\/a><\/li><li class=\"elementor-sitemap-item elementor-sitemap-item-page page_item page-item-3653\"><a href=\"https:\/\/www.arssenasa.gob.do\/index.php\/formulario-solicitud\/\">Formulario Solicitud de Empleo<\/a><\/li><li class=\"elementor-sitemap-item elementor-sitemap-item-page page_item page-item-10309\"><a href=\"https:\/\/www.arssenasa.gob.do\/index.php\/elementor-10309\/\">SeNaSa se Transforma<\/a><\/li><li class=\"elementor-sitemap-item elementor-sitemap-item-page page_item page-item-14667\"><a href=\"https:\/\/www.arssenasa.gob.do\/index.php\/elementor-14667\/\">Senasa reduce riesgos a trav\u00e9s de sus diferentes programas  en pacientes con diabetes<\/a><\/li><li class=\"elementor-sitemap-item elementor-sitemap-item-page page_item page-item-22605\"><a href=\"https:\/\/www.arssenasa.gob.do\/index.php\/senasa-integra\/\">Programa SeNaSa inTEgrA<\/a><\/li><li class=\"elementor-sitemap-item elementor-sitemap-item-page page_item page-item-593\"><a href=\"https:\/\/www.arssenasa.gob.do\/\">Inicio<\/a><\/li><li class=\"elementor-sitemap-item elementor-sitemap-item-page page_item page-item-18523\"><a href=\"https:\/\/www.arssenasa.gob.do\/index.php\/guia-autorizaciones-medicas-ova\/\">Gu\u00eda Autorizaciones M\u00e9dicas &#8211; OVA<\/a><\/li><li class=\"elementor-sitemap-item elementor-sitemap-item-page page_item page-item-2913\"><a href=\"https:\/\/www.arssenasa.gob.do\/index.php\/seise\/\">SEISE 2019<\/a><\/li><li class=\"elementor-sitemap-item elementor-sitemap-item-page page_item page-item-356\"><a href=\"https:\/\/www.arssenasa.gob.do\/index.php\/contactos\/\">Contactos<\/a><\/li><li class=\"elementor-sitemap-item elementor-sitemap-item-page page_item page-item-16259\"><a href=\"https:\/\/www.arssenasa.gob.do\/index.php\/elementor-16259\/\">Semana Santa 2023<\/a><\/li><li class=\"elementor-sitemap-item elementor-sitemap-item-page page_item page-item-21129\"><a href=\"https:\/\/www.arssenasa.gob.do\/index.php\/404-2\/\">404<\/a><\/li><li class=\"elementor-sitemap-item elementor-sitemap-item-page page_item page-item-1677\"><a href=\"https:\/\/www.arssenasa.gob.do\/index.php\/plan-larimar\/\">Plan Larimar<\/a><\/li><li class=\"elementor-sitemap-item elementor-sitemap-item-page page_item page-item-915\"><a href=\"https:\/\/www.arssenasa.gob.do\/index.php\/conoce-tus-derechos\/\">Conoce tus derechos<\/a><\/li><li class=\"elementor-sitemap-item elementor-sitemap-item-page page_item page-item-8597\"><a href=\"https:\/\/www.arssenasa.gob.do\/index.php\/planes-complementarios\/\">Planes Complementarios y Opcionales<\/a><\/li><li class=\"elementor-sitemap-item elementor-sitemap-item-page page_item page-item-665\"><a href=\"https:\/\/www.arssenasa.gob.do\/index.php\/preguntasfrecuentes\/\">Preguntas Frecuentes<\/a><\/li><li class=\"elementor-sitemap-item elementor-sitemap-item-page page_item page-item-3737\"><a href=\"https:\/\/www.arssenasa.gob.do\/index.php\/covid-19\/\">COVID-19<\/a><\/li><li class=\"elementor-sitemap-item elementor-sitemap-item-page page_item page-item-3242\"><a href=\"https:\/\/www.arssenasa.gob.do\/index.php\/policias-y-militares\/\">Polic\u00edas y Militares<\/a><\/li><li class=\"elementor-sitemap-item elementor-sitemap-item-page page_item page-item-10410\"><a href=\"https:\/\/www.arssenasa.gob.do\/index.php\/dia-internacional-de-la-mujer\/\">D\u00eda Internacional de la Mujer<\/a><\/li><li class=\"elementor-sitemap-item elementor-sitemap-item-page page_item page-item-12970\"><a href=\"https:\/\/www.arssenasa.gob.do\/index.php\/landing-larimar\/\">Larimar<\/a><\/li><li class=\"elementor-sitemap-item elementor-sitemap-item-page page_item page-item-14508\"><a href=\"https:\/\/www.arssenasa.gob.do\/index.php\/organigrama\/\">Organigrama<\/a><\/li><li class=\"elementor-sitemap-item elementor-sitemap-item-page page_item page-item-19382\"><a href=\"https:\/\/www.arssenasa.gob.do\/index.php\/politicas-de-privacidad-app-senasa\/\">Pol\u00edticas de Privacidad &#8211; App SeNaSa<\/a><\/li><li class=\"elementor-sitemap-item elementor-sitemap-item-page page_item page-item-2745\"><a href=\"https:\/\/www.arssenasa.gob.do\/index.php\/foro-senasa\/\">Comunidad SeNaSa<\/a><\/li><li class=\"elementor-sitemap-item elementor-sitemap-item-page page_item page-item-9145\"><a href=\"https:\/\/www.arssenasa.gob.do\/index.php\/recicla-y-vive-mejor\/\">Recicla y Vive Mejor<\/a><\/li><li class=\"elementor-sitemap-item elementor-sitemap-item-page page_item page-item-19137\"><a href=\"https:\/\/www.arssenasa.gob.do\/index.php\/memoria-institucional-2023-2024\/\">Memoria Institucional 2023-2024<\/a><\/li><li class=\"elementor-sitemap-item elementor-sitemap-item-page page_item page-item-16839\"><a href=\"https:\/\/www.arssenasa.gob.do\/index.php\/semana-innovacion-senasa-2023\/\">Semana de la Innovaci\u00f3n SeNaSa 2023<\/a><\/li><li class=\"elementor-sitemap-item elementor-sitemap-item-page page_item page-item-19657\"><a href=\"https:\/\/www.arssenasa.gob.do\/index.php\/app-senasa-short\/\">App SeNaSa short<\/a><\/li><li class=\"elementor-sitemap-item elementor-sitemap-item-page page_item page-item-2257\"><a href=\"https:\/\/www.arssenasa.gob.do\/index.php\/gracias\/\">Gracias por contactarnos<\/a><\/li><li class=\"elementor-sitemap-item elementor-sitemap-item-page page_item page-item-985\"><a href=\"https:\/\/www.arssenasa.gob.do\/index.php\/regimen-subsidiado\/\">R\u00e9gimen Subsidiado<\/a><ul class='children'><li class=\"elementor-sitemap-item elementor-sitemap-item-page page_item page-item-22277\"><a href=\"https:\/\/www.arssenasa.gob.do\/index.php\/regimen-subsidiado\/cobertura-regimen-subsidiado\/\">Cobertura R\u00e9gimen Subsidiado<\/a><\/li><li class=\"elementor-sitemap-item elementor-sitemap-item-page page_item page-item-4942\"><a href=\"https:\/\/www.arssenasa.gob.do\/index.php\/regimen-subsidiado\/jornadas-de-afiliacion\/\">Jornadas de Afiliaci\u00f3n<\/a><\/li><li class=\"elementor-sitemap-item elementor-sitemap-item-page page_item page-item-5976\"><a href=\"https:\/\/www.arssenasa.gob.do\/index.php\/regimen-subsidiado\/programas-de-salud\/\">Programas de Salud<\/a><\/li><li class=\"elementor-sitemap-item elementor-sitemap-item-page page_item page-item-2498\"><a href=\"https:\/\/www.arssenasa.gob.do\/index.php\/regimen-subsidiado\/rs-cobertura\/\">R\u00e9gimen Subsidiado al D\u00eda<\/a><\/li><li class=\"elementor-sitemap-item elementor-sitemap-item-page page_item page-item-2503\"><a href=\"https:\/\/www.arssenasa.gob.do\/index.php\/regimen-subsidiado\/rs-afiliacion\/\">Afiliaci\u00f3n al R\u00e9gimen Subsidiado<\/a><\/li><li class=\"elementor-sitemap-item elementor-sitemap-item-page page_item page-item-2507\"><a href=\"https:\/\/www.arssenasa.gob.do\/index.php\/regimen-subsidiado\/rs-derechosydeberes\/\">Beneficios, Derechos y Deberes del RS<\/a><\/li><li class=\"elementor-sitemap-item elementor-sitemap-item-page page_item page-item-2770\"><a href=\"https:\/\/www.arssenasa.gob.do\/index.php\/regimen-subsidiado\/informate\/\">Inf\u00f3rmate<\/a><\/li><li class=\"elementor-sitemap-item elementor-sitemap-item-page page_item page-item-2777\"><a href=\"https:\/\/www.arssenasa.gob.do\/index.php\/regimen-subsidiado\/vida-saludable\/\">Vida Saludable<\/a><\/li><\/ul><\/li><li class=\"elementor-sitemap-item elementor-sitemap-item-page page_item page-item-21482\"><a href=\"https:\/\/www.arssenasa.gob.do\/index.php\/mayoria-de-edad\/\">Mayor\u00eda de Edad<\/a><\/li><li class=\"elementor-sitemap-item elementor-sitemap-item-page page_item page-item-17899\"><a href=\"https:\/\/www.arssenasa.gob.do\/index.php\/videos-institucionales\/\">V\u00eddeos Institucionales<\/a><\/li><li class=\"elementor-sitemap-item elementor-sitemap-item-page page_item page-item-1004\"><a href=\"https:\/\/www.arssenasa.gob.do\/index.php\/pensionados-jubilados\/\">Pensionados y Jubilados<\/a><\/li><li class=\"elementor-sitemap-item elementor-sitemap-item-page page_item page-item-17901\"><a href=\"https:\/\/www.arssenasa.gob.do\/index.php\/canales-derivados\/\">Canales Derivados<\/a><\/li><li class=\"elementor-sitemap-item elementor-sitemap-item-page page_item page-item-20983\"><a href=\"https:\/\/www.arssenasa.gob.do\/index.php\/aviso\/\">Aviso<\/a><\/li><li class=\"elementor-sitemap-item elementor-sitemap-item-page page_item page-item-2044\"><a href=\"https:\/\/www.arssenasa.gob.do\/index.php\/accesibilidad\/\">Accesibilidad<\/a><\/li><li class=\"elementor-sitemap-item elementor-sitemap-item-page page_item page-item-17405\"><a href=\"https:\/\/www.arssenasa.gob.do\/index.php\/canales-alternos\/\">Canales Alternos<\/a><\/li><\/ul><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"","protected":false},"author":3,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"inline_featured_image":false,"yasr_overall_rating":0,"yasr_post_is_review":"","yasr_auto_insert_disabled":"","yasr_review_type":"","_glsr_average":0,"_glsr_ranking":0,"_glsr_reviews":0,"footnotes":""},"class_list":["post-281","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Mapa del Sitio - ARSSeNaSa<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.arssenasa.gob.do\/index.php\/mapadelsitio\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mapa del Sitio - ARSSeNaSa\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.arssenasa.gob.do\/index.php\/mapadelsitio\/\" \/>\n<meta property=\"og:site_name\" content=\"ARSSeNaSa\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ARSSeNaSaRD\" \/>\n<meta property=\"article:modified_time\" content=\"2022-03-25T20:01:01+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@arssenasard\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.arssenasa.gob.do\/index.php\/mapadelsitio\/\",\"url\":\"https:\/\/www.arssenasa.gob.do\/index.php\/mapadelsitio\/\",\"name\":\"Mapa del Sitio - ARSSeNaSa\",\"isPartOf\":{\"@id\":\"https:\/\/www.arssenasa.gob.do\/#website\"},\"datePublished\":\"2018-11-07T12:30:41+00:00\",\"dateModified\":\"2022-03-25T20:01:01+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.arssenasa.gob.do\/index.php\/mapadelsitio\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.arssenasa.gob.do\/index.php\/mapadelsitio\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.arssenasa.gob.do\/index.php\/mapadelsitio\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\/\/www.arssenasa.gob.do\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mapa del Sitio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.arssenasa.gob.do\/#website\",\"url\":\"https:\/\/www.arssenasa.gob.do\/\",\"name\":\"ARSSeNaSa\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.arssenasa.gob.do\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.arssenasa.gob.do\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.arssenasa.gob.do\/#organization\",\"name\":\"SeNaSa - Seguro Nacional de Salud\",\"url\":\"https:\/\/www.arssenasa.gob.do\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.arssenasa.gob.do\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.arssenasa.gob.do\/wp-content\/uploads\/2018\/11\/logo2022.png\",\"contentUrl\":\"https:\/\/www.arssenasa.gob.do\/wp-content\/uploads\/2018\/11\/logo2022.png\",\"width\":310,\"height\":200,\"caption\":\"SeNaSa - Seguro Nacional de Salud\"},\"image\":{\"@id\":\"https:\/\/www.arssenasa.gob.do\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/ARSSeNaSaRD\",\"https:\/\/x.com\/arssenasard\",\"https:\/\/www.instagram.com\/arssenasard\/\",\"https:\/\/www.youtube.com\/user\/ARSSeNaSa\"]},false]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mapa del Sitio - ARSSeNaSa","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.arssenasa.gob.do\/index.php\/mapadelsitio\/","og_locale":"es_ES","og_type":"article","og_title":"Mapa del Sitio - ARSSeNaSa","og_url":"https:\/\/www.arssenasa.gob.do\/index.php\/mapadelsitio\/","og_site_name":"ARSSeNaSa","article_publisher":"https:\/\/www.facebook.com\/ARSSeNaSaRD","article_modified_time":"2022-03-25T20:01:01+00:00","twitter_card":"summary_large_image","twitter_site":"@arssenasard","twitter_misc":{"Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.arssenasa.gob.do\/index.php\/mapadelsitio\/","url":"https:\/\/www.arssenasa.gob.do\/index.php\/mapadelsitio\/","name":"Mapa del Sitio - ARSSeNaSa","isPartOf":{"@id":"https:\/\/www.arssenasa.gob.do\/#website"},"datePublished":"2018-11-07T12:30:41+00:00","dateModified":"2022-03-25T20:01:01+00:00","breadcrumb":{"@id":"https:\/\/www.arssenasa.gob.do\/index.php\/mapadelsitio\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.arssenasa.gob.do\/index.php\/mapadelsitio\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.arssenasa.gob.do\/index.php\/mapadelsitio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.arssenasa.gob.do\/"},{"@type":"ListItem","position":2,"name":"Mapa del Sitio"}]},{"@type":"WebSite","@id":"https:\/\/www.arssenasa.gob.do\/#website","url":"https:\/\/www.arssenasa.gob.do\/","name":"ARSSeNaSa","description":"","publisher":{"@id":"https:\/\/www.arssenasa.gob.do\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.arssenasa.gob.do\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.arssenasa.gob.do\/#organization","name":"SeNaSa - Seguro Nacional de Salud","url":"https:\/\/www.arssenasa.gob.do\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.arssenasa.gob.do\/#\/schema\/logo\/image\/","url":"https:\/\/www.arssenasa.gob.do\/wp-content\/uploads\/2018\/11\/logo2022.png","contentUrl":"https:\/\/www.arssenasa.gob.do\/wp-content\/uploads\/2018\/11\/logo2022.png","width":310,"height":200,"caption":"SeNaSa - Seguro Nacional de Salud"},"image":{"@id":"https:\/\/www.arssenasa.gob.do\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ARSSeNaSaRD","https:\/\/x.com\/arssenasard","https:\/\/www.instagram.com\/arssenasard\/","https:\/\/www.youtube.com\/user\/ARSSeNaSa"]},false]}},"yasr_visitor_votes":{"stars_attributes":{"read_only":false,"span_bottom":false},"number_of_votes":0,"sum_votes":0},"_links":{"self":[{"href":"https:\/\/www.arssenasa.gob.do\/index.php\/wp-json\/wp\/v2\/pages\/281","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.arssenasa.gob.do\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.arssenasa.gob.do\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.arssenasa.gob.do\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.arssenasa.gob.do\/index.php\/wp-json\/wp\/v2\/comments?post=281"}],"version-history":[{"count":23,"href":"https:\/\/www.arssenasa.gob.do\/index.php\/wp-json\/wp\/v2\/pages\/281\/revisions"}],"predecessor-version":[{"id":11405,"href":"https:\/\/www.arssenasa.gob.do\/index.php\/wp-json\/wp\/v2\/pages\/281\/revisions\/11405"}],"wp:attachment":[{"href":"https:\/\/www.arssenasa.gob.do\/index.php\/wp-json\/wp\/v2\/media?parent=281"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}