{"id":3542,"date":"2020-02-14T14:25:38","date_gmt":"2020-02-14T18:25:38","guid":{"rendered":"https:\/\/www.arssenasa.gob.do\/?page_id=3542"},"modified":"2021-03-04T15:17:25","modified_gmt":"2021-03-04T19:17:25","slug":"afiliacion-dependiente-alcanza-mayoria-de-edad","status":"publish","type":"page","link":"https:\/\/www.arssenasa.gob.do\/index.php\/servicios\/servicios-regimen-subsidiado-2\/afiliacion-dependiente-alcanza-mayoria-de-edad\/","title":{"rendered":"Afiliaci\u00f3n Dependiente Alcanza Mayor\u00eda de Edad"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"3542\" class=\"elementor elementor-3542\" data-elementor-settings=\"{&quot;ha_cmc_init_switcher&quot;:&quot;no&quot;}\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c183185 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c183185\" data-element_type=\"section\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-2c25047\" data-id=\"2c25047\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4482394 elementor-widget elementor-widget-heading\" data-id=\"4482394\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\">Servios R\u00e9gimen Subsidiado<\/h6>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-17002a2 elementor-nav-menu__align-start elementor-nav-menu--dropdown-tablet elementor-nav-menu__text-align-aside elementor-widget elementor-widget-nav-menu\" data-id=\"17002a2\" data-element_type=\"widget\" data-settings=\"{&quot;layout&quot;:&quot;vertical&quot;,&quot;submenu_icon&quot;:{&quot;value&quot;:&quot;&lt;i aria-hidden=\\&quot;true\\&quot; class=\\&quot;\\&quot;&gt;&lt;\\\/i&gt;&quot;,&quot;library&quot;:&quot;&quot;}}\" data-widget_type=\"nav-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<nav aria-label=\"Menu\" class=\"elementor-nav-menu--main elementor-nav-menu__container elementor-nav-menu--layout-vertical e--pointer-background e--animation-fade\">\n\t\t\t\t<ul id=\"menu-1-17002a2\" class=\"elementor-nav-menu sm-vertical\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-3525\"><a href=\"https:\/\/www.arssenasa.gob.do\/index.php\/servicios\/servicios-regimen-subsidiado-2\/solicitud-de-afiliacion-titular-al-regimen-subsidiado\/\" class=\"elementor-item\">Solicitud de Afiliaci\u00f3n Titular al R\u00e9gimen Subsidiado<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-3529\"><a href=\"https:\/\/www.arssenasa.gob.do\/index.php\/servicios\/servicios-regimen-subsidiado-2\/pre-autorizacion-de-servicios-de-alto-costo-sin-materiales\/\" class=\"elementor-item\">Preautorizaci\u00f3n de Servicios de Salud<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-3533\"><a href=\"https:\/\/www.arssenasa.gob.do\/index.php\/servicios\/servicios-regimen-subsidiado-2\/afiliacion-dependientes-directos-esposos-e-hijos-menores\/\" class=\"elementor-item\">Afiliaci\u00f3n Dependientes Directos (esposos e hijos o hijastros menores)<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-3541\"><a href=\"https:\/\/www.arssenasa.gob.do\/index.php\/servicios\/servicios-regimen-subsidiado-2\/afiliacion-hijos-con-discapacidad\/\" class=\"elementor-item\">Afiliaci\u00f3n Hijos con Discapacidad<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-4268\"><a href=\"https:\/\/www.arssenasa.gob.do\/index.php\/servicios\/servicios-regimen-subsidiado-2\/imprimir-carta-de-afiliacion\/\" class=\"elementor-item\">Impresi\u00f3n Carta de Afiliaci\u00f3n<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-16637\"><a href=\"https:\/\/www.arssenasa.gob.do\/index.php\/servicios\/servicios-regimen-subsidiado-2\/solicitud-de-reembolso-de-servicios-de-salud\/\" class=\"elementor-item\">Solicitud de Reembolso de Servicios de Salud<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t\t<nav class=\"elementor-nav-menu--dropdown elementor-nav-menu__container\" aria-hidden=\"true\">\n\t\t\t\t<ul id=\"menu-2-17002a2\" class=\"elementor-nav-menu sm-vertical\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-3525\"><a href=\"https:\/\/www.arssenasa.gob.do\/index.php\/servicios\/servicios-regimen-subsidiado-2\/solicitud-de-afiliacion-titular-al-regimen-subsidiado\/\" class=\"elementor-item\" tabindex=\"-1\">Solicitud de Afiliaci\u00f3n Titular al R\u00e9gimen Subsidiado<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-3529\"><a href=\"https:\/\/www.arssenasa.gob.do\/index.php\/servicios\/servicios-regimen-subsidiado-2\/pre-autorizacion-de-servicios-de-alto-costo-sin-materiales\/\" class=\"elementor-item\" tabindex=\"-1\">Preautorizaci\u00f3n de Servicios de Salud<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-3533\"><a href=\"https:\/\/www.arssenasa.gob.do\/index.php\/servicios\/servicios-regimen-subsidiado-2\/afiliacion-dependientes-directos-esposos-e-hijos-menores\/\" class=\"elementor-item\" tabindex=\"-1\">Afiliaci\u00f3n Dependientes Directos (esposos e hijos o hijastros menores)<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-3541\"><a href=\"https:\/\/www.arssenasa.gob.do\/index.php\/servicios\/servicios-regimen-subsidiado-2\/afiliacion-hijos-con-discapacidad\/\" class=\"elementor-item\" tabindex=\"-1\">Afiliaci\u00f3n Hijos con Discapacidad<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-4268\"><a href=\"https:\/\/www.arssenasa.gob.do\/index.php\/servicios\/servicios-regimen-subsidiado-2\/imprimir-carta-de-afiliacion\/\" class=\"elementor-item\" tabindex=\"-1\">Impresi\u00f3n Carta de Afiliaci\u00f3n<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-16637\"><a href=\"https:\/\/www.arssenasa.gob.do\/index.php\/servicios\/servicios-regimen-subsidiado-2\/solicitud-de-reembolso-de-servicios-de-salud\/\" class=\"elementor-item\" tabindex=\"-1\">Solicitud de Reembolso de Servicios de Salud<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-07bac18\" data-id=\"07bac18\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-9f3b89a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9f3b89a\" data-element_type=\"section\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-b6fb38e\" data-id=\"b6fb38e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-07b3685 elementor-widget elementor-widget-breadcrumbs\" data-id=\"07b3685\" data-element_type=\"widget\" data-widget_type=\"breadcrumbs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p id=\"breadcrumbs\"><span><span><a href=\"https:\/\/www.arssenasa.gob.do\/\">Inicio<\/a><\/span><\/span><\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-56ee6bc\" data-id=\"56ee6bc\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6f07c27 elementor-share-buttons--view-icon elementor-share-buttons--skin-minimal elementor-share-buttons--shape-circle elementor-grid-0 elementor-share-buttons--color-official elementor-widget elementor-widget-share-buttons\" data-id=\"6f07c27\" data-element_type=\"widget\" data-widget_type=\"share-buttons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-grid\" role=\"list\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t\t<div class=\"elementor-share-btn elementor-share-btn_print\" role=\"button\" tabindex=\"0\" aria-label=\"Share on print\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__icon\">\n\t\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-print\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M448 192V77.25c0-8.49-3.37-16.62-9.37-22.63L393.37 9.37c-6-6-14.14-9.37-22.63-9.37H96C78.33 0 64 14.33 64 32v160c-35.35 0-64 28.65-64 64v112c0 8.84 7.16 16 16 16h48v96c0 17.67 14.33 32 32 32h320c17.67 0 32-14.33 32-32v-96h48c8.84 0 16-7.16 16-16V256c0-35.35-28.65-64-64-64zm-64 256H128v-96h256v96zm0-224H128V64h192v48c0 8.84 7.16 16 16 16h48v96zm48 72c-13.25 0-24-10.75-24-24 0-13.26 10.75-24 24-24s24 10.74 24 24c0 13.25-10.75 24-24 24z\"><\/path><\/svg>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t\t<div class=\"elementor-share-btn elementor-share-btn_email\" role=\"button\" tabindex=\"0\" aria-label=\"Share on email\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__icon\">\n\t\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-envelope\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M502.3 190.8c3.9-3.1 9.7-.2 9.7 4.7V400c0 26.5-21.5 48-48 48H48c-26.5 0-48-21.5-48-48V195.6c0-5 5.7-7.8 9.7-4.7 22.4 17.4 52.1 39.5 154.1 113.6 21.1 15.4 56.7 47.8 92.2 47.6 35.7.3 72-32.8 92.3-47.6 102-74.1 131.6-96.3 154-113.7zM256 320c23.2.4 56.6-29.2 73.4-41.4 132.7-96.3 142.8-104.7 173.4-128.7 5.8-4.5 9.2-11.5 9.2-18.9v-19c0-26.5-21.5-48-48-48H48C21.5 64 0 85.5 0 112v19c0 7.4 3.4 14.3 9.2 18.9 30.6 23.9 40.7 32.4 173.4 128.7 16.8 12.2 50.2 41.8 73.4 41.4z\"><\/path><\/svg>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-62e5493 elementor-widget elementor-widget-text-editor\" data-id=\"62e5493\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Descripci\u00f3n del servicio<\/strong><\/p><p>Este servicio est\u00e1 dirigido para todos nuestros afiliados que quieran re-afiliar a sus dependientes que han alcanzado la mayor\u00eda de edad.<\/p><p><strong>A qui\u00e9n va dirigido<\/strong><\/p><p>R\u00e9gimen Contributivo y R\u00e9gimen Subsidiado<\/p><p><strong>\u00c1rea Responsable<\/strong><\/p><p>Gerencia de Atenci\u00f3n al Usuario y Prestadores<\/p><p><strong>Nombre del Encargado del \u00c1rea Responsable<\/strong><\/p><p>Roberto Canaan Acta<\/p><p><strong>Tel\u00e9fono<\/strong><\/p><p>809-701-3821 opci\u00f3n 3, desde cualquier opci\u00f3n pueden marcar 0 para contacto con un auxiliar de servicio<\/p><p><strong>Fax<\/strong><\/p><p>809-793-2607<\/p><p><strong>Correo electr\u00f3nico<\/strong><\/p><p><a href=\"mailto:info@arssenasa.gob.do\"><span style=\"color: #47a951;\">info@arssenasa.gob.do<\/span><\/a><\/p><p><b>Requerimientos o requisitos<\/b><\/p><p>&#8211; Copia de la C\u00e9dula del titular<br \/>&#8211; Certificaci\u00f3n de estudio del dependiente<br \/>&#8211; Acta de nacimiento<\/p><p><strong>Procedimiento<\/strong><\/p><p>El afiliado se dirige a una de nuestras oficinas con los requisitos detallados y all\u00ed es asistido por uno de nuestros auxiliares de servicios. Auxiliar registra el caso en el m\u00f3dulo de Atenci\u00f3n al Usuario y entrega Acuse de Recibo, con el tiempo estimado para otorgarle respuesta.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-3d7b8da elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3d7b8da\" data-element_type=\"section\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-bbc0875\" data-id=\"bbc0875\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-48d3a43 elementor-widget elementor-widget-text-editor\" data-id=\"48d3a43\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><img decoding=\"async\" class=\"aligncenter size-full wp-image-542\" src=\"https:\/\/www.arssenasa.gob.do\/wp-content\/uploads\/2018\/11\/horario.png\" alt=\"\" width=\"43\" height=\"42\" \/><br \/><strong>Horario de prestaci\u00f3n:<\/strong><br \/>Informaci\u00f3n disponible en nuestro\u00a0<span style=\"color: #47a951;\"><a style=\"color: #47a951;\" href=\"https:\/\/www.arssenasa.gob.do\/index.php\/oficinas-y-puntos-de-servicios\/\">lista de oficinas<\/a><\/span>.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-e2908c7\" data-id=\"e2908c7\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3228c51 elementor-widget elementor-widget-text-editor\" data-id=\"3228c51\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><img decoding=\"async\" class=\"aligncenter size-full wp-image-543\" src=\"https:\/\/www.arssenasa.gob.do\/wp-content\/uploads\/2018\/11\/costo.png\" alt=\"\" width=\"43\" height=\"42\"><strong><br>Costo:<\/strong> Gratis<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-a085c58\" data-id=\"a085c58\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6fa8e85 elementor-widget elementor-widget-text-editor\" data-id=\"6fa8e85\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><img decoding=\"async\" class=\"aligncenter size-full wp-image-544\" src=\"https:\/\/www.arssenasa.gob.do\/wp-content\/uploads\/2018\/11\/tiempo.png\" alt=\"\" width=\"43\" height=\"42\" \/><br \/><strong>Tiempo de realizaci\u00f3n: <br \/><\/strong>30 a 45 d\u00edas laborables.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-7d6dedd\" data-id=\"7d6dedd\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-97ba7d3 elementor-widget elementor-widget-text-editor\" data-id=\"97ba7d3\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-545\" src=\"https:\/\/www.arssenasa.gob.do\/wp-content\/uploads\/2018\/11\/web.png\" alt=\"\" width=\"43\" height=\"42\" \/><br \/><strong>Canal de prestaci\u00f3n:<\/strong><br \/>Presencial<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-db85055 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"db85055\" data-element_type=\"section\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-f625d36\" data-id=\"f625d36\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-867c338 elementor-widget elementor-widget-facebook-comments\" data-id=\"867c338\" data-element_type=\"widget\" data-widget_type=\"facebook-comments.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-facebook-widget fb-comments\" data-href=\"https:\/\/www.arssenasa.gob.do?p=3542\" data-width=\"100%\" data-numposts=\"10\" data-order-by=\"social\" style=\"min-height: 1px\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Servios R\u00e9gimen Subsidiado Share on print Share on email Descripci\u00f3n del servicio Este servicio est\u00e1 dirigido para todos nuestros afiliados que quieran re-afiliar a sus dependientes que han alcanzado la mayor\u00eda de edad. A qui\u00e9n va dirigido R\u00e9gimen Contributivo y R\u00e9gimen Subsidiado \u00c1rea Responsable Gerencia de Atenci\u00f3n al Usuario y Prestadores Nombre del Encargado del [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"parent":578,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"inline_featured_image":false,"yasr_overall_rating":0,"yasr_post_is_review":"","yasr_auto_insert_disabled":"","yasr_review_type":"","_glsr_average":0,"_glsr_ranking":0,"_glsr_reviews":0,"footnotes":""},"class_list":["post-3542","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Afiliaci\u00f3n Dependiente Alcanza Mayor\u00eda de Edad - ARSSeNaSa<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.arssenasa.gob.do\/index.php\/servicios\/servicios-regimen-subsidiado-2\/afiliacion-dependiente-alcanza-mayoria-de-edad\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Afiliaci\u00f3n Dependiente Alcanza Mayor\u00eda de Edad - ARSSeNaSa\" \/>\n<meta property=\"og:description\" content=\"Servios R\u00e9gimen Subsidiado Share on print Share on email Descripci\u00f3n del servicio Este servicio est\u00e1 dirigido para todos nuestros afiliados que quieran re-afiliar a sus dependientes que han alcanzado la mayor\u00eda de edad. A qui\u00e9n va dirigido R\u00e9gimen Contributivo y R\u00e9gimen Subsidiado \u00c1rea Responsable Gerencia de Atenci\u00f3n al Usuario y Prestadores Nombre del Encargado del [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.arssenasa.gob.do\/index.php\/servicios\/servicios-regimen-subsidiado-2\/afiliacion-dependiente-alcanza-mayoria-de-edad\/\" \/>\n<meta property=\"og:site_name\" content=\"ARSSeNaSa\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ARSSeNaSaRD\" \/>\n<meta property=\"article:modified_time\" content=\"2021-03-04T19:17:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.arssenasa.gob.do\/wp-content\/uploads\/2018\/11\/horario.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@arssenasard\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.arssenasa.gob.do\/index.php\/servicios\/servicios-regimen-subsidiado-2\/afiliacion-dependiente-alcanza-mayoria-de-edad\/\",\"url\":\"https:\/\/www.arssenasa.gob.do\/index.php\/servicios\/servicios-regimen-subsidiado-2\/afiliacion-dependiente-alcanza-mayoria-de-edad\/\",\"name\":\"Afiliaci\u00f3n Dependiente Alcanza Mayor\u00eda de Edad - ARSSeNaSa\",\"isPartOf\":{\"@id\":\"https:\/\/www.arssenasa.gob.do\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.arssenasa.gob.do\/index.php\/servicios\/servicios-regimen-subsidiado-2\/afiliacion-dependiente-alcanza-mayoria-de-edad\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.arssenasa.gob.do\/index.php\/servicios\/servicios-regimen-subsidiado-2\/afiliacion-dependiente-alcanza-mayoria-de-edad\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.arssenasa.gob.do\/wp-content\/uploads\/2018\/11\/horario.png\",\"datePublished\":\"2020-02-14T18:25:38+00:00\",\"dateModified\":\"2021-03-04T19:17:25+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.arssenasa.gob.do\/index.php\/servicios\/servicios-regimen-subsidiado-2\/afiliacion-dependiente-alcanza-mayoria-de-edad\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.arssenasa.gob.do\/index.php\/servicios\/servicios-regimen-subsidiado-2\/afiliacion-dependiente-alcanza-mayoria-de-edad\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.arssenasa.gob.do\/index.php\/servicios\/servicios-regimen-subsidiado-2\/afiliacion-dependiente-alcanza-mayoria-de-edad\/#primaryimage\",\"url\":\"https:\/\/www.arssenasa.gob.do\/wp-content\/uploads\/2018\/11\/horario.png\",\"contentUrl\":\"https:\/\/www.arssenasa.gob.do\/wp-content\/uploads\/2018\/11\/horario.png\",\"width\":43,\"height\":42,\"caption\":\"Icono Horario\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.arssenasa.gob.do\/index.php\/servicios\/servicios-regimen-subsidiado-2\/afiliacion-dependiente-alcanza-mayoria-de-edad\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\/\/www.arssenasa.gob.do\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Servicios\",\"item\":\"https:\/\/www.arssenasa.gob.do\/index.php\/servicios\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Servicios R\u00e9gimen Subsidiado\",\"item\":\"https:\/\/www.arssenasa.gob.do\/index.php\/servicios\/servicios-regimen-subsidiado-2\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Afiliaci\u00f3n Dependiente Alcanza Mayor\u00eda de Edad\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.arssenasa.gob.do\/#website\",\"url\":\"https:\/\/www.arssenasa.gob.do\/\",\"name\":\"ARSSeNaSa\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.arssenasa.gob.do\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.arssenasa.gob.do\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.arssenasa.gob.do\/#organization\",\"name\":\"SeNaSa - Seguro Nacional de Salud\",\"url\":\"https:\/\/www.arssenasa.gob.do\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.arssenasa.gob.do\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.arssenasa.gob.do\/wp-content\/uploads\/2018\/11\/logo2022.png\",\"contentUrl\":\"https:\/\/www.arssenasa.gob.do\/wp-content\/uploads\/2018\/11\/logo2022.png\",\"width\":310,\"height\":200,\"caption\":\"SeNaSa - Seguro Nacional de Salud\"},\"image\":{\"@id\":\"https:\/\/www.arssenasa.gob.do\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/ARSSeNaSaRD\",\"https:\/\/x.com\/arssenasard\",\"https:\/\/www.instagram.com\/arssenasard\/\",\"https:\/\/www.youtube.com\/user\/ARSSeNaSa\"]},false]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Afiliaci\u00f3n Dependiente Alcanza Mayor\u00eda de Edad - ARSSeNaSa","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.arssenasa.gob.do\/index.php\/servicios\/servicios-regimen-subsidiado-2\/afiliacion-dependiente-alcanza-mayoria-de-edad\/","og_locale":"es_ES","og_type":"article","og_title":"Afiliaci\u00f3n Dependiente Alcanza Mayor\u00eda de Edad - ARSSeNaSa","og_description":"Servios R\u00e9gimen Subsidiado Share on print Share on email Descripci\u00f3n del servicio Este servicio est\u00e1 dirigido para todos nuestros afiliados que quieran re-afiliar a sus dependientes que han alcanzado la mayor\u00eda de edad. A qui\u00e9n va dirigido R\u00e9gimen Contributivo y R\u00e9gimen Subsidiado \u00c1rea Responsable Gerencia de Atenci\u00f3n al Usuario y Prestadores Nombre del Encargado del [&hellip;]","og_url":"https:\/\/www.arssenasa.gob.do\/index.php\/servicios\/servicios-regimen-subsidiado-2\/afiliacion-dependiente-alcanza-mayoria-de-edad\/","og_site_name":"ARSSeNaSa","article_publisher":"https:\/\/www.facebook.com\/ARSSeNaSaRD","article_modified_time":"2021-03-04T19:17:25+00:00","og_image":[{"url":"https:\/\/www.arssenasa.gob.do\/wp-content\/uploads\/2018\/11\/horario.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_site":"@arssenasard","twitter_misc":{"Est. reading time":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.arssenasa.gob.do\/index.php\/servicios\/servicios-regimen-subsidiado-2\/afiliacion-dependiente-alcanza-mayoria-de-edad\/","url":"https:\/\/www.arssenasa.gob.do\/index.php\/servicios\/servicios-regimen-subsidiado-2\/afiliacion-dependiente-alcanza-mayoria-de-edad\/","name":"Afiliaci\u00f3n Dependiente Alcanza Mayor\u00eda de Edad - ARSSeNaSa","isPartOf":{"@id":"https:\/\/www.arssenasa.gob.do\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.arssenasa.gob.do\/index.php\/servicios\/servicios-regimen-subsidiado-2\/afiliacion-dependiente-alcanza-mayoria-de-edad\/#primaryimage"},"image":{"@id":"https:\/\/www.arssenasa.gob.do\/index.php\/servicios\/servicios-regimen-subsidiado-2\/afiliacion-dependiente-alcanza-mayoria-de-edad\/#primaryimage"},"thumbnailUrl":"https:\/\/www.arssenasa.gob.do\/wp-content\/uploads\/2018\/11\/horario.png","datePublished":"2020-02-14T18:25:38+00:00","dateModified":"2021-03-04T19:17:25+00:00","breadcrumb":{"@id":"https:\/\/www.arssenasa.gob.do\/index.php\/servicios\/servicios-regimen-subsidiado-2\/afiliacion-dependiente-alcanza-mayoria-de-edad\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.arssenasa.gob.do\/index.php\/servicios\/servicios-regimen-subsidiado-2\/afiliacion-dependiente-alcanza-mayoria-de-edad\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.arssenasa.gob.do\/index.php\/servicios\/servicios-regimen-subsidiado-2\/afiliacion-dependiente-alcanza-mayoria-de-edad\/#primaryimage","url":"https:\/\/www.arssenasa.gob.do\/wp-content\/uploads\/2018\/11\/horario.png","contentUrl":"https:\/\/www.arssenasa.gob.do\/wp-content\/uploads\/2018\/11\/horario.png","width":43,"height":42,"caption":"Icono Horario"},{"@type":"BreadcrumbList","@id":"https:\/\/www.arssenasa.gob.do\/index.php\/servicios\/servicios-regimen-subsidiado-2\/afiliacion-dependiente-alcanza-mayoria-de-edad\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.arssenasa.gob.do\/"},{"@type":"ListItem","position":2,"name":"Servicios","item":"https:\/\/www.arssenasa.gob.do\/index.php\/servicios\/"},{"@type":"ListItem","position":3,"name":"Servicios R\u00e9gimen Subsidiado","item":"https:\/\/www.arssenasa.gob.do\/index.php\/servicios\/servicios-regimen-subsidiado-2\/"},{"@type":"ListItem","position":4,"name":"Afiliaci\u00f3n Dependiente Alcanza Mayor\u00eda de Edad"}]},{"@type":"WebSite","@id":"https:\/\/www.arssenasa.gob.do\/#website","url":"https:\/\/www.arssenasa.gob.do\/","name":"ARSSeNaSa","description":"","publisher":{"@id":"https:\/\/www.arssenasa.gob.do\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.arssenasa.gob.do\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.arssenasa.gob.do\/#organization","name":"SeNaSa - Seguro Nacional de Salud","url":"https:\/\/www.arssenasa.gob.do\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.arssenasa.gob.do\/#\/schema\/logo\/image\/","url":"https:\/\/www.arssenasa.gob.do\/wp-content\/uploads\/2018\/11\/logo2022.png","contentUrl":"https:\/\/www.arssenasa.gob.do\/wp-content\/uploads\/2018\/11\/logo2022.png","width":310,"height":200,"caption":"SeNaSa - Seguro Nacional de Salud"},"image":{"@id":"https:\/\/www.arssenasa.gob.do\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ARSSeNaSaRD","https:\/\/x.com\/arssenasard","https:\/\/www.instagram.com\/arssenasard\/","https:\/\/www.youtube.com\/user\/ARSSeNaSa"]},false]}},"yasr_visitor_votes":{"stars_attributes":{"read_only":false,"span_bottom":false},"number_of_votes":29,"sum_votes":113},"_links":{"self":[{"href":"https:\/\/www.arssenasa.gob.do\/index.php\/wp-json\/wp\/v2\/pages\/3542","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.arssenasa.gob.do\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.arssenasa.gob.do\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.arssenasa.gob.do\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.arssenasa.gob.do\/index.php\/wp-json\/wp\/v2\/comments?post=3542"}],"version-history":[{"count":17,"href":"https:\/\/www.arssenasa.gob.do\/index.php\/wp-json\/wp\/v2\/pages\/3542\/revisions"}],"predecessor-version":[{"id":8318,"href":"https:\/\/www.arssenasa.gob.do\/index.php\/wp-json\/wp\/v2\/pages\/3542\/revisions\/8318"}],"up":[{"embeddable":true,"href":"https:\/\/www.arssenasa.gob.do\/index.php\/wp-json\/wp\/v2\/pages\/578"}],"wp:attachment":[{"href":"https:\/\/www.arssenasa.gob.do\/index.php\/wp-json\/wp\/v2\/media?parent=3542"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}