{"id":915,"date":"2018-12-10T15:52:06","date_gmt":"2018-12-10T19:52:06","guid":{"rendered":"http:\/\/192.168.1.138\/wordpress\/?page_id=915"},"modified":"2022-03-25T15:51:03","modified_gmt":"2022-03-25T19:51:03","slug":"conoce-tus-derechos","status":"publish","type":"page","link":"https:\/\/www.arssenasa.gob.do\/index.php\/conoce-tus-derechos\/","title":{"rendered":"Conoce tus derechos"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"915\" class=\"elementor elementor-915\" data-elementor-settings=\"{&quot;ha_cmc_init_switcher&quot;:&quot;no&quot;}\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-48babdca elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"48babdca\" data-element_type=\"section\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7709316a\" data-id=\"7709316a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-54173958 elementor-widget elementor-widget-text-editor\" data-id=\"54173958\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><\/p>\n<figure class=\"wp-block-image\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"541\" class=\"wp-image-775 aligncenter\" src=\"http:\/\/www.arssenasa.gob.do\/wp-content\/uploads\/2018\/11\/Deberes-y-Derechos-1024x541.jpg\" alt=\"\" srcset=\"https:\/\/www.arssenasa.gob.do\/wp-content\/uploads\/2018\/11\/Deberes-y-Derechos-1024x541.jpg 1024w, https:\/\/www.arssenasa.gob.do\/wp-content\/uploads\/2018\/11\/Deberes-y-Derechos-300x158.jpg 300w, https:\/\/www.arssenasa.gob.do\/wp-content\/uploads\/2018\/11\/Deberes-y-Derechos-768x406.jpg 768w, https:\/\/www.arssenasa.gob.do\/wp-content\/uploads\/2018\/11\/Deberes-y-Derechos.jpg 1242w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<p><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"","protected":false},"author":3,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"inline_featured_image":false,"yasr_overall_rating":0,"yasr_post_is_review":"","yasr_auto_insert_disabled":"","yasr_review_type":"","_glsr_average":0,"_glsr_ranking":0,"_glsr_reviews":0,"footnotes":""},"class_list":["post-915","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Conoce tus derechos - ARSSeNaSa<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.arssenasa.gob.do\/index.php\/conoce-tus-derechos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Conoce tus derechos - ARSSeNaSa\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.arssenasa.gob.do\/index.php\/conoce-tus-derechos\/\" \/>\n<meta property=\"og:site_name\" content=\"ARSSeNaSa\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ARSSeNaSaRD\" \/>\n<meta property=\"article:modified_time\" content=\"2022-03-25T19:51:03+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.arssenasa.gob.do\/wp-content\/uploads\/2018\/11\/Deberes-y-Derechos-1024x541.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@arssenasard\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.arssenasa.gob.do\/index.php\/conoce-tus-derechos\/\",\"url\":\"https:\/\/www.arssenasa.gob.do\/index.php\/conoce-tus-derechos\/\",\"name\":\"Conoce tus derechos - ARSSeNaSa\",\"isPartOf\":{\"@id\":\"https:\/\/www.arssenasa.gob.do\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.arssenasa.gob.do\/index.php\/conoce-tus-derechos\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.arssenasa.gob.do\/index.php\/conoce-tus-derechos\/#primaryimage\"},\"thumbnailUrl\":\"http:\/\/www.arssenasa.gob.do\/wp-content\/uploads\/2018\/11\/Deberes-y-Derechos-1024x541.jpg\",\"datePublished\":\"2018-12-10T19:52:06+00:00\",\"dateModified\":\"2022-03-25T19:51:03+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.arssenasa.gob.do\/index.php\/conoce-tus-derechos\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.arssenasa.gob.do\/index.php\/conoce-tus-derechos\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.arssenasa.gob.do\/index.php\/conoce-tus-derechos\/#primaryimage\",\"url\":\"http:\/\/www.arssenasa.gob.do\/wp-content\/uploads\/2018\/11\/Deberes-y-Derechos-1024x541.jpg\",\"contentUrl\":\"http:\/\/www.arssenasa.gob.do\/wp-content\/uploads\/2018\/11\/Deberes-y-Derechos-1024x541.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.arssenasa.gob.do\/index.php\/conoce-tus-derechos\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\/\/www.arssenasa.gob.do\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Conoce tus derechos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.arssenasa.gob.do\/#website\",\"url\":\"https:\/\/www.arssenasa.gob.do\/\",\"name\":\"ARSSeNaSa\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.arssenasa.gob.do\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.arssenasa.gob.do\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.arssenasa.gob.do\/#organization\",\"name\":\"SeNaSa - Seguro Nacional de Salud\",\"url\":\"https:\/\/www.arssenasa.gob.do\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.arssenasa.gob.do\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.arssenasa.gob.do\/wp-content\/uploads\/2018\/11\/logo2022.png\",\"contentUrl\":\"https:\/\/www.arssenasa.gob.do\/wp-content\/uploads\/2018\/11\/logo2022.png\",\"width\":310,\"height\":200,\"caption\":\"SeNaSa - Seguro Nacional de Salud\"},\"image\":{\"@id\":\"https:\/\/www.arssenasa.gob.do\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/ARSSeNaSaRD\",\"https:\/\/x.com\/arssenasard\",\"https:\/\/www.instagram.com\/arssenasard\/\",\"https:\/\/www.youtube.com\/user\/ARSSeNaSa\"]},false]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Conoce tus derechos - ARSSeNaSa","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.arssenasa.gob.do\/index.php\/conoce-tus-derechos\/","og_locale":"es_ES","og_type":"article","og_title":"Conoce tus derechos - ARSSeNaSa","og_url":"https:\/\/www.arssenasa.gob.do\/index.php\/conoce-tus-derechos\/","og_site_name":"ARSSeNaSa","article_publisher":"https:\/\/www.facebook.com\/ARSSeNaSaRD","article_modified_time":"2022-03-25T19:51:03+00:00","og_image":[{"url":"http:\/\/www.arssenasa.gob.do\/wp-content\/uploads\/2018\/11\/Deberes-y-Derechos-1024x541.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_site":"@arssenasard","twitter_misc":{"Est. reading time":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.arssenasa.gob.do\/index.php\/conoce-tus-derechos\/","url":"https:\/\/www.arssenasa.gob.do\/index.php\/conoce-tus-derechos\/","name":"Conoce tus derechos - ARSSeNaSa","isPartOf":{"@id":"https:\/\/www.arssenasa.gob.do\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.arssenasa.gob.do\/index.php\/conoce-tus-derechos\/#primaryimage"},"image":{"@id":"https:\/\/www.arssenasa.gob.do\/index.php\/conoce-tus-derechos\/#primaryimage"},"thumbnailUrl":"http:\/\/www.arssenasa.gob.do\/wp-content\/uploads\/2018\/11\/Deberes-y-Derechos-1024x541.jpg","datePublished":"2018-12-10T19:52:06+00:00","dateModified":"2022-03-25T19:51:03+00:00","breadcrumb":{"@id":"https:\/\/www.arssenasa.gob.do\/index.php\/conoce-tus-derechos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.arssenasa.gob.do\/index.php\/conoce-tus-derechos\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.arssenasa.gob.do\/index.php\/conoce-tus-derechos\/#primaryimage","url":"http:\/\/www.arssenasa.gob.do\/wp-content\/uploads\/2018\/11\/Deberes-y-Derechos-1024x541.jpg","contentUrl":"http:\/\/www.arssenasa.gob.do\/wp-content\/uploads\/2018\/11\/Deberes-y-Derechos-1024x541.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.arssenasa.gob.do\/index.php\/conoce-tus-derechos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.arssenasa.gob.do\/"},{"@type":"ListItem","position":2,"name":"Conoce tus derechos"}]},{"@type":"WebSite","@id":"https:\/\/www.arssenasa.gob.do\/#website","url":"https:\/\/www.arssenasa.gob.do\/","name":"ARSSeNaSa","description":"","publisher":{"@id":"https:\/\/www.arssenasa.gob.do\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.arssenasa.gob.do\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.arssenasa.gob.do\/#organization","name":"SeNaSa - Seguro Nacional de Salud","url":"https:\/\/www.arssenasa.gob.do\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.arssenasa.gob.do\/#\/schema\/logo\/image\/","url":"https:\/\/www.arssenasa.gob.do\/wp-content\/uploads\/2018\/11\/logo2022.png","contentUrl":"https:\/\/www.arssenasa.gob.do\/wp-content\/uploads\/2018\/11\/logo2022.png","width":310,"height":200,"caption":"SeNaSa - Seguro Nacional de Salud"},"image":{"@id":"https:\/\/www.arssenasa.gob.do\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ARSSeNaSaRD","https:\/\/x.com\/arssenasard","https:\/\/www.instagram.com\/arssenasard\/","https:\/\/www.youtube.com\/user\/ARSSeNaSa"]},false]}},"yasr_visitor_votes":{"stars_attributes":{"read_only":false,"span_bottom":false},"number_of_votes":0,"sum_votes":0},"_links":{"self":[{"href":"https:\/\/www.arssenasa.gob.do\/index.php\/wp-json\/wp\/v2\/pages\/915","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.arssenasa.gob.do\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.arssenasa.gob.do\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.arssenasa.gob.do\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.arssenasa.gob.do\/index.php\/wp-json\/wp\/v2\/comments?post=915"}],"version-history":[{"count":6,"href":"https:\/\/www.arssenasa.gob.do\/index.php\/wp-json\/wp\/v2\/pages\/915\/revisions"}],"predecessor-version":[{"id":11382,"href":"https:\/\/www.arssenasa.gob.do\/index.php\/wp-json\/wp\/v2\/pages\/915\/revisions\/11382"}],"wp:attachment":[{"href":"https:\/\/www.arssenasa.gob.do\/index.php\/wp-json\/wp\/v2\/media?parent=915"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}