{"id":12220,"date":"2022-04-06T09:39:11","date_gmt":"2022-04-06T13:39:11","guid":{"rendered":"https:\/\/www.arssenasa.gob.do\/?p=12220"},"modified":"2022-04-06T09:39:13","modified_gmt":"2022-04-06T13:39:13","slug":"senasa-celebra-la-semana-de-la-innovacion","status":"publish","type":"post","link":"https:\/\/www.arssenasa.gob.do\/index.php\/blog\/2022\/04\/06\/senasa-celebra-la-semana-de-la-innovacion\/","title":{"rendered":"SeNaSa celebra la Semana de la innovaci\u00f3n"},"content":{"rendered":"\n<p><strong>Santo Domingo. \u2013<\/strong> El Seguro Nacional de Salud (SeNaSa), como instituci\u00f3n l\u00edder en calidad e innovaci\u00f3n del servicio p\u00fablico, inici\u00f3 este a\u00f1o la celebraci\u00f3n de la Semana de la Innovaci\u00f3n con el tema \u201cPr\u00e1cticas Disruptivas en la Administraci\u00f3n de Riesgos y Servicios de Salud\u201d, en la que se estuvieron presentando los principales avances en materia de prestaci\u00f3n de servicios a sus afiliados e interesados, adem\u00e1s de diversas charlas sobre la importancia de la innovaci\u00f3n en el sector p\u00fablico y en el \u00e1mbito de la seguridad social dominicana.<\/p>\n\n\n\n<p>Durante esta actividad se mostraron las metas y resultados SeNaSa, como la afiliaci\u00f3n masiva de los ciudadanos al seguro familiar de salud, la creaci\u00f3n de un plan de salud para los dominicanos en el exterior, los planes de reforzamiento de la cultura de servicio y la implementaci\u00f3n del efecto wao en todos los servicios que brinda la instituci\u00f3n.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/www.arssenasa.gob.do\/wp-content\/uploads\/2022\/04\/02-12-1024x682.jpg\" alt=\"Dr. Santiago Hazim durante su discurso\" class=\"wp-image-12253\" srcset=\"https:\/\/www.arssenasa.gob.do\/wp-content\/uploads\/2022\/04\/02-12-1024x682.jpg 1024w, https:\/\/www.arssenasa.gob.do\/wp-content\/uploads\/2022\/04\/02-12-300x200.jpg 300w, https:\/\/www.arssenasa.gob.do\/wp-content\/uploads\/2022\/04\/02-12-768x512.jpg 768w, https:\/\/www.arssenasa.gob.do\/wp-content\/uploads\/2022\/04\/02-12.jpg 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption>Dr. Santiago Hazim durante su discurso<\/figcaption><\/figure><\/div>\n\n\n\n<p>Las palabras centrales estuvieron a cargo del Dr. Santiago Hazim, director ejecutivo de SeNaSa, quien dijo que \u201cEs un placer para m\u00ed estar aqu\u00ed, siendo parte de la apertura de la Semana de la Innovaci\u00f3n, que es un evento que algunos pa\u00edses desarrollan en el mes de abril de cada a\u00f1o para promover la innovaci\u00f3n y la ciencia; y por supuesto, el Seguro Nacional de Salud (SeNaSa), como instituci\u00f3n l\u00edder en calidad e innovaci\u00f3n del servicio p\u00fablico y en seguros de riesgos de salud, no pod\u00eda quedarse atr\u00e1s\u201d.<\/p>\n\n\n\n<p>Esta actividad se suma a otras iniciativas, tales como la semana de la calidad, iniciada en noviembre del 2020 y posteriormente, una segunda edici\u00f3n en noviembre del a\u00f1o 2021.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/www.arssenasa.gob.do\/wp-content\/uploads\/2022\/04\/03-9-1024x682.jpg\" alt=\"P\u00fablico asistente\" class=\"wp-image-12257\" srcset=\"https:\/\/www.arssenasa.gob.do\/wp-content\/uploads\/2022\/04\/03-9-1024x682.jpg 1024w, https:\/\/www.arssenasa.gob.do\/wp-content\/uploads\/2022\/04\/03-9-300x200.jpg 300w, https:\/\/www.arssenasa.gob.do\/wp-content\/uploads\/2022\/04\/03-9-768x512.jpg 768w, https:\/\/www.arssenasa.gob.do\/wp-content\/uploads\/2022\/04\/03-9-1536x1023.jpg 1536w, https:\/\/www.arssenasa.gob.do\/wp-content\/uploads\/2022\/04\/03-9.jpg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption>P\u00fablico asistente<\/figcaption><\/figure><\/div>\n\n\n\n<h3 class=\"wp-block-heading\">Logros alcanzados<\/h3>\n\n\n\n<p>\u2022 Afiliaci\u00f3n de m\u00e1s de 2 millones de afiliados al r\u00e9gimen subsidiado del Seguro Familiar de Salud.<\/p>\n\n\n\n<p>\u2022 Medalla de ORO en el Premio Iberoamericano a la Calidad, resultado del compromiso con la implementaci\u00f3n de un modelo de excelencia y calidad en la gesti\u00f3n.<\/p>\n\n\n\n<p>\u2022 Ganar el 1er lugar en el marat\u00f3n de innovaci\u00f3n gubernamental, auspiciado por el MAPRE y el OGTIC, destac\u00e1ndonos con el aporte de ideas y soluciones innovadoras para mejorar el tiempo de autorizaciones en los servicios de alto costo.<\/p>\n\n\n\n<p>\u2022 Disponibilidad de los Servicios en un 100% a pesar de la pandemia del COVID 19 y la incorporaci\u00f3n del 100% del personal al servicio presencial.<\/p>\n\n\n\n<p>\u2022 Hemos capacitado y certificado en la norma ISO 37301:2021 sobre cumplimiento regulatorio a m\u00e1s de 20 l\u00edderes dentro de la instituci\u00f3n que han fortalecido la red de cumplimiento regulatorio en toda la organizaci\u00f3n.<\/p>\n\n\n\n<p>\u2022 Evaluaci\u00f3n y reevaluaci\u00f3n de los proveedores de bienes y servicios, as\u00ed como de y prestadores de servicios de salud que correspond\u00eda al 2020, m\u00e1s lo que corresponden al a\u00f1o 2021.<\/p>\n\n\n\n<p>\u2022 La recertificaci\u00f3n del sistema de gesti\u00f3n de calidad bajo la norma ISO 9001:2015 por primera vez con 0 no conformidades mayores o menores, sin observaciones y s\u00ed, con 8 oportunidades de mejora. Esta auditor\u00eda de recertificaci\u00f3n realizada por parte del INDOCAL, autoridad nacional responsable de la normalizaci\u00f3n en la Rep\u00fablica Dominicana, aportando as\u00ed a fortalecer las instituciones nacionales en el desarrollo y consolidaci\u00f3n del rol para las que fueron creadas.<\/p>\n\n\n\n<p>\u2022 Contar con una red de m\u00e1s de 8 mil prestadores a nivel nacional.<\/p>\n\n\n\n<p>\u2022 Hemos logrado la certificaci\u00f3n de la norma Nortic A4 en nuestro sitio Web.<\/p>\n\n\n\n<p>\u2022 Hemos recibido el premio del PNUD y del gobierno dominicano por logro de los objetivos de desarrollo sostenible ODS-3 por lograr la universalizaci\u00f3n del acceso a los servicios de salud.<\/p>\n\n\n\n<p>\u2022 Actualmente SeNaSa implementa un sistema, bajo la norma ISO 37001:2016, que proporciona una gu\u00eda para establecer y fortalecer un sistema de gesti\u00f3n antisoborno. Como parte de esta norma, hemos capacitado un equipo estrat\u00e9gico dentro de la organizaci\u00f3n para concienciarlos sobre las normas antisoborno, los riesgos de la corrupci\u00f3n, canales de denuncia, entre otros aspectos importantes en el marco de la cultura \u00e9tica y de valores que nos caracteriza.<\/p>\n\n\n\n<p>\u2022 Como parte de las acciones de SeNaSa en el Exterior, pr\u00f3ximamente estaremos presentando un plan de salud especial para los dominicanos que viven fuera del pa\u00eds y, adem\u00e1s, estaremos inaugurando nuevas oficinas de SeNaSa en Estados Unidos para que todos los dominicanos puedan acceder a este seguro y a servicios de salud dignos sin importar en qu\u00e9 lugar se encuentren.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Santo Domingo. \u2013 El Seguro Nacional de Salud (SeNaSa), como instituci\u00f3n l\u00edder en calidad e innovaci\u00f3n del servicio p\u00fablico, inici\u00f3 este a\u00f1o la celebraci\u00f3n de la Semana de la Innovaci\u00f3n con el tema \u201cPr\u00e1cticas Disruptivas en la Administraci\u00f3n de Riesgos y Servicios de Salud\u201d, en la que se estuvieron presentando los principales avances en materia [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":12225,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"yasr_overall_rating":0,"yasr_post_is_review":"","yasr_auto_insert_disabled":"","yasr_review_type":"","_glsr_average":0,"_glsr_ranking":0,"_glsr_reviews":0,"footnotes":""},"categories":[13],"tags":[],"class_list":["post-12220","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>SeNaSa celebra la Semana de la innovaci\u00f3n - ARSSeNaSa<\/title>\n<meta name=\"description\" content=\"%\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.arssenasa.gob.do\/index.php\/blog\/2022\/04\/06\/senasa-celebra-la-semana-de-la-innovacion\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"SeNaSa celebra la Semana de la innovaci\u00f3n - ARSSeNaSa\" \/>\n<meta property=\"og:description\" content=\"%\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.arssenasa.gob.do\/index.php\/blog\/2022\/04\/06\/senasa-celebra-la-semana-de-la-innovacion\/\" \/>\n<meta property=\"og:site_name\" content=\"ARSSeNaSa\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ARSSeNaSaRD\" \/>\n<meta property=\"article:published_time\" content=\"2022-04-06T13:39:11+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-04-06T13:39:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.arssenasa.gob.do\/wp-content\/uploads\/2022\/04\/01-11.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"853\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"SeNaSa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@arssenasard\" \/>\n<meta name=\"twitter:site\" content=\"@arssenasard\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"SeNaSa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.arssenasa.gob.do\/index.php\/blog\/2022\/04\/06\/senasa-celebra-la-semana-de-la-innovacion\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.arssenasa.gob.do\/index.php\/blog\/2022\/04\/06\/senasa-celebra-la-semana-de-la-innovacion\/\"},\"author\":{\"name\":\"SeNaSa\",\"@id\":\"https:\/\/www.arssenasa.gob.do\/#\/schema\/person\/b9d6c2c58f44cdecdcdaab7a6f9504c0\"},\"headline\":\"SeNaSa celebra la Semana de la innovaci\u00f3n\",\"datePublished\":\"2022-04-06T13:39:11+00:00\",\"dateModified\":\"2022-04-06T13:39:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.arssenasa.gob.do\/index.php\/blog\/2022\/04\/06\/senasa-celebra-la-semana-de-la-innovacion\/\"},\"wordCount\":752,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.arssenasa.gob.do\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.arssenasa.gob.do\/index.php\/blog\/2022\/04\/06\/senasa-celebra-la-semana-de-la-innovacion\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.arssenasa.gob.do\/wp-content\/uploads\/2022\/04\/01-11.jpg\",\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.arssenasa.gob.do\/index.php\/blog\/2022\/04\/06\/senasa-celebra-la-semana-de-la-innovacion\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.arssenasa.gob.do\/index.php\/blog\/2022\/04\/06\/senasa-celebra-la-semana-de-la-innovacion\/\",\"url\":\"https:\/\/www.arssenasa.gob.do\/index.php\/blog\/2022\/04\/06\/senasa-celebra-la-semana-de-la-innovacion\/\",\"name\":\"SeNaSa celebra la Semana de la innovaci\u00f3n - ARSSeNaSa\",\"isPartOf\":{\"@id\":\"https:\/\/www.arssenasa.gob.do\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.arssenasa.gob.do\/index.php\/blog\/2022\/04\/06\/senasa-celebra-la-semana-de-la-innovacion\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.arssenasa.gob.do\/index.php\/blog\/2022\/04\/06\/senasa-celebra-la-semana-de-la-innovacion\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.arssenasa.gob.do\/wp-content\/uploads\/2022\/04\/01-11.jpg\",\"datePublished\":\"2022-04-06T13:39:11+00:00\",\"dateModified\":\"2022-04-06T13:39:13+00:00\",\"description\":\"%\",\"breadcrumb\":{\"@id\":\"https:\/\/www.arssenasa.gob.do\/index.php\/blog\/2022\/04\/06\/senasa-celebra-la-semana-de-la-innovacion\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.arssenasa.gob.do\/index.php\/blog\/2022\/04\/06\/senasa-celebra-la-semana-de-la-innovacion\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.arssenasa.gob.do\/index.php\/blog\/2022\/04\/06\/senasa-celebra-la-semana-de-la-innovacion\/#primaryimage\",\"url\":\"https:\/\/www.arssenasa.gob.do\/wp-content\/uploads\/2022\/04\/01-11.jpg\",\"contentUrl\":\"https:\/\/www.arssenasa.gob.do\/wp-content\/uploads\/2022\/04\/01-11.jpg\",\"width\":1280,\"height\":853,\"caption\":\"Enmanuel Rodr\u00edguez, Gustavo G\u00fcilamo, Santiago Hazim y Kinller Moquete\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.arssenasa.gob.do\/index.php\/blog\/2022\/04\/06\/senasa-celebra-la-semana-de-la-innovacion\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\/\/www.arssenasa.gob.do\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"SeNaSa celebra la Semana de la innovaci\u00f3n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.arssenasa.gob.do\/#website\",\"url\":\"https:\/\/www.arssenasa.gob.do\/\",\"name\":\"ARSSeNaSa\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.arssenasa.gob.do\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.arssenasa.gob.do\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.arssenasa.gob.do\/#organization\",\"name\":\"SeNaSa - Seguro Nacional de Salud\",\"url\":\"https:\/\/www.arssenasa.gob.do\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.arssenasa.gob.do\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.arssenasa.gob.do\/wp-content\/uploads\/2018\/11\/logo2022.png\",\"contentUrl\":\"https:\/\/www.arssenasa.gob.do\/wp-content\/uploads\/2018\/11\/logo2022.png\",\"width\":310,\"height\":200,\"caption\":\"SeNaSa - Seguro Nacional de Salud\"},\"image\":{\"@id\":\"https:\/\/www.arssenasa.gob.do\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/ARSSeNaSaRD\",\"https:\/\/x.com\/arssenasard\",\"https:\/\/www.instagram.com\/arssenasard\/\",\"https:\/\/www.youtube.com\/user\/ARSSeNaSa\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.arssenasa.gob.do\/#\/schema\/person\/b9d6c2c58f44cdecdcdaab7a6f9504c0\",\"name\":\"SeNaSa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.arssenasa.gob.do\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/3c45125f46520136bb5577344179f8312f2704a1174137df27ae1baa182b5a6e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/3c45125f46520136bb5577344179f8312f2704a1174137df27ae1baa182b5a6e?s=96&d=mm&r=g\",\"caption\":\"SeNaSa\"},\"url\":\"https:\/\/www.arssenasa.gob.do\/index.php\/blog\/author\/admin\/\"},false]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"SeNaSa celebra la Semana de la innovaci\u00f3n - ARSSeNaSa","description":"%","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.arssenasa.gob.do\/index.php\/blog\/2022\/04\/06\/senasa-celebra-la-semana-de-la-innovacion\/","og_locale":"es_ES","og_type":"article","og_title":"SeNaSa celebra la Semana de la innovaci\u00f3n - ARSSeNaSa","og_description":"%","og_url":"https:\/\/www.arssenasa.gob.do\/index.php\/blog\/2022\/04\/06\/senasa-celebra-la-semana-de-la-innovacion\/","og_site_name":"ARSSeNaSa","article_publisher":"https:\/\/www.facebook.com\/ARSSeNaSaRD","article_published_time":"2022-04-06T13:39:11+00:00","article_modified_time":"2022-04-06T13:39:13+00:00","og_image":[{"width":1280,"height":853,"url":"https:\/\/www.arssenasa.gob.do\/wp-content\/uploads\/2022\/04\/01-11.jpg","type":"image\/jpeg"}],"author":"SeNaSa","twitter_card":"summary_large_image","twitter_creator":"@arssenasard","twitter_site":"@arssenasard","twitter_misc":{"Written by":"SeNaSa","Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.arssenasa.gob.do\/index.php\/blog\/2022\/04\/06\/senasa-celebra-la-semana-de-la-innovacion\/#article","isPartOf":{"@id":"https:\/\/www.arssenasa.gob.do\/index.php\/blog\/2022\/04\/06\/senasa-celebra-la-semana-de-la-innovacion\/"},"author":{"name":"SeNaSa","@id":"https:\/\/www.arssenasa.gob.do\/#\/schema\/person\/b9d6c2c58f44cdecdcdaab7a6f9504c0"},"headline":"SeNaSa celebra la Semana de la innovaci\u00f3n","datePublished":"2022-04-06T13:39:11+00:00","dateModified":"2022-04-06T13:39:13+00:00","mainEntityOfPage":{"@id":"https:\/\/www.arssenasa.gob.do\/index.php\/blog\/2022\/04\/06\/senasa-celebra-la-semana-de-la-innovacion\/"},"wordCount":752,"commentCount":0,"publisher":{"@id":"https:\/\/www.arssenasa.gob.do\/#organization"},"image":{"@id":"https:\/\/www.arssenasa.gob.do\/index.php\/blog\/2022\/04\/06\/senasa-celebra-la-semana-de-la-innovacion\/#primaryimage"},"thumbnailUrl":"https:\/\/www.arssenasa.gob.do\/wp-content\/uploads\/2022\/04\/01-11.jpg","articleSection":["Noticias"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.arssenasa.gob.do\/index.php\/blog\/2022\/04\/06\/senasa-celebra-la-semana-de-la-innovacion\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.arssenasa.gob.do\/index.php\/blog\/2022\/04\/06\/senasa-celebra-la-semana-de-la-innovacion\/","url":"https:\/\/www.arssenasa.gob.do\/index.php\/blog\/2022\/04\/06\/senasa-celebra-la-semana-de-la-innovacion\/","name":"SeNaSa celebra la Semana de la innovaci\u00f3n - ARSSeNaSa","isPartOf":{"@id":"https:\/\/www.arssenasa.gob.do\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.arssenasa.gob.do\/index.php\/blog\/2022\/04\/06\/senasa-celebra-la-semana-de-la-innovacion\/#primaryimage"},"image":{"@id":"https:\/\/www.arssenasa.gob.do\/index.php\/blog\/2022\/04\/06\/senasa-celebra-la-semana-de-la-innovacion\/#primaryimage"},"thumbnailUrl":"https:\/\/www.arssenasa.gob.do\/wp-content\/uploads\/2022\/04\/01-11.jpg","datePublished":"2022-04-06T13:39:11+00:00","dateModified":"2022-04-06T13:39:13+00:00","description":"%","breadcrumb":{"@id":"https:\/\/www.arssenasa.gob.do\/index.php\/blog\/2022\/04\/06\/senasa-celebra-la-semana-de-la-innovacion\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.arssenasa.gob.do\/index.php\/blog\/2022\/04\/06\/senasa-celebra-la-semana-de-la-innovacion\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.arssenasa.gob.do\/index.php\/blog\/2022\/04\/06\/senasa-celebra-la-semana-de-la-innovacion\/#primaryimage","url":"https:\/\/www.arssenasa.gob.do\/wp-content\/uploads\/2022\/04\/01-11.jpg","contentUrl":"https:\/\/www.arssenasa.gob.do\/wp-content\/uploads\/2022\/04\/01-11.jpg","width":1280,"height":853,"caption":"Enmanuel Rodr\u00edguez, Gustavo G\u00fcilamo, Santiago Hazim y Kinller Moquete"},{"@type":"BreadcrumbList","@id":"https:\/\/www.arssenasa.gob.do\/index.php\/blog\/2022\/04\/06\/senasa-celebra-la-semana-de-la-innovacion\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.arssenasa.gob.do\/"},{"@type":"ListItem","position":2,"name":"SeNaSa celebra la Semana de la innovaci\u00f3n"}]},{"@type":"WebSite","@id":"https:\/\/www.arssenasa.gob.do\/#website","url":"https:\/\/www.arssenasa.gob.do\/","name":"ARSSeNaSa","description":"","publisher":{"@id":"https:\/\/www.arssenasa.gob.do\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.arssenasa.gob.do\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.arssenasa.gob.do\/#organization","name":"SeNaSa - Seguro Nacional de Salud","url":"https:\/\/www.arssenasa.gob.do\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.arssenasa.gob.do\/#\/schema\/logo\/image\/","url":"https:\/\/www.arssenasa.gob.do\/wp-content\/uploads\/2018\/11\/logo2022.png","contentUrl":"https:\/\/www.arssenasa.gob.do\/wp-content\/uploads\/2018\/11\/logo2022.png","width":310,"height":200,"caption":"SeNaSa - Seguro Nacional de Salud"},"image":{"@id":"https:\/\/www.arssenasa.gob.do\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ARSSeNaSaRD","https:\/\/x.com\/arssenasard","https:\/\/www.instagram.com\/arssenasard\/","https:\/\/www.youtube.com\/user\/ARSSeNaSa"]},{"@type":"Person","@id":"https:\/\/www.arssenasa.gob.do\/#\/schema\/person\/b9d6c2c58f44cdecdcdaab7a6f9504c0","name":"SeNaSa","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.arssenasa.gob.do\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/3c45125f46520136bb5577344179f8312f2704a1174137df27ae1baa182b5a6e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3c45125f46520136bb5577344179f8312f2704a1174137df27ae1baa182b5a6e?s=96&d=mm&r=g","caption":"SeNaSa"},"url":"https:\/\/www.arssenasa.gob.do\/index.php\/blog\/author\/admin\/"},false]}},"yasr_visitor_votes":{"stars_attributes":{"read_only":false,"span_bottom":false},"number_of_votes":0,"sum_votes":0},"_links":{"self":[{"href":"https:\/\/www.arssenasa.gob.do\/index.php\/wp-json\/wp\/v2\/posts\/12220","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.arssenasa.gob.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.arssenasa.gob.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.arssenasa.gob.do\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.arssenasa.gob.do\/index.php\/wp-json\/wp\/v2\/comments?post=12220"}],"version-history":[{"count":1,"href":"https:\/\/www.arssenasa.gob.do\/index.php\/wp-json\/wp\/v2\/posts\/12220\/revisions"}],"predecessor-version":[{"id":12258,"href":"https:\/\/www.arssenasa.gob.do\/index.php\/wp-json\/wp\/v2\/posts\/12220\/revisions\/12258"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.arssenasa.gob.do\/index.php\/wp-json\/wp\/v2\/media\/12225"}],"wp:attachment":[{"href":"https:\/\/www.arssenasa.gob.do\/index.php\/wp-json\/wp\/v2\/media?parent=12220"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.arssenasa.gob.do\/index.php\/wp-json\/wp\/v2\/categories?post=12220"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.arssenasa.gob.do\/index.php\/wp-json\/wp\/v2\/tags?post=12220"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}