{"id":1622,"date":"2019-01-28T16:35:58","date_gmt":"2019-01-28T20:35:58","guid":{"rendered":"http:\/\/192.168.1.138\/wordpress\/?p=1622"},"modified":"2019-03-19T11:06:02","modified_gmt":"2019-03-19T15:06:02","slug":"el-paso-de-los-empleados-publicos-a-senasa-es-constitucional-senasa-reafirma-esta-mas-que-lista-para-recibirlos","status":"publish","type":"post","link":"https:\/\/www.arssenasa.gob.do\/index.php\/blog\/2019\/01\/28\/el-paso-de-los-empleados-publicos-a-senasa-es-constitucional-senasa-reafirma-esta-mas-que-lista-para-recibirlos\/","title":{"rendered":"El paso de los empleados p\u00fablicos a SeNaSa es constitucional; SeNaSa reafirma est\u00e1 m\u00e1s que lista para recibirlos"},"content":{"rendered":"\n<p style=\"text-align:center\">SeNaSa est\u00e1 m\u00e1s que lista para recibir a los empleados p\u00fablicos. La ARS estatal explica no hace falta una sentencia para que los empleados p\u00fablicos sean afiliados a ella, ya que la Ley No. 87-01, en su art\u00edculo 31, as\u00ed lo establece.<\/p>\n\n\n\n<p>Santo Domingo-. El Seguro Nacional de Salud (SeNaSa) explic\u00f3 que el traspaso de los empleados p\u00fablicos a la ARS estatal es legal, conforme al art\u00edculo 31 de la Ley No. 87-01, el cual establece que SeNaSa tendr\u00e1 a su cargo a todos los empleados de las instituciones p\u00fablicas, aut\u00f3nomas o descentralizadas y a sus familiares directos, por lo que no existen impedimentos jur\u00eddicos ni la ilegalidad argumentados por la Asociaci\u00f3n Dominicana de Administradoras de Riesgos de Salud (ADARS).<\/p>\n\n\n\n<p>La doctora Mercedes Rodr\u00edguez Silver, directora ejecutiva de SeNaSa, indic\u00f3 que el principio de libre elecci\u00f3n no es violado con el traspaso de los empleados p\u00fablicos a la ARS p\u00fablica, ya que su alcance est\u00e1 limitado por la propia Ley No. 87-01, que crea el Sistema Dominicano de Seguridad Social, la cual dispone la afiliaci\u00f3n de los empleados p\u00fablicos a dicha instituci\u00f3n.<\/p>\n\n\n\n<p>\u201cEl traspaso de los empleados p\u00fablicos a SeNaSa tampoco es inconstitucional, ya que el alcance del art\u00edculo 39 de la Constituci\u00f3n sobre el derecho a la igualdad se cumple, al permitir a todos los empleados del sector privado elegir su Administradora de Riesgos de Salud y a los Prestadores de Servicios de Salud\u201d, explic\u00f3 la doctora Rodr\u00edguez Silver, al tiempo que agreg\u00f3 que ese art\u00edculo tambi\u00e9n establece los l\u00edmites legales.<\/p>\n\n\n\n<p>Tanto la sentencia No. 61-2012 de la Suprema Corte de Justicia como la No. 0573-2018 del Tribunal Constitucional afirman que el art\u00edculo 31 de la Ley 87-01 es constitucional, agreg\u00f3 la funcionaria.<\/p>\n\n\n\n<p><strong>Traspaso garantizar\u00e1 derechos de afiliados<\/strong><\/p>\n\n\n\n<p>El traspaso de los empleados p\u00fablicos a SeNaSa se realizar\u00e1 bajo los lineamientos que establezca la Superintendencia de Salud y Riesgos Laborales (SISALRIL), de manera paulatina y sin vulnerar los derechos de los afiliados.<\/p>\n\n\n\n<p><strong>Gesti\u00f3n orientada a la excelencia<\/strong><\/p>\n\n\n\n<p>SeNaSa cuenta con la capacidad para garantizar servicios de calidad a sus afiliados, exhibiendo altos est\u00e1ndares de calidad en la gesti\u00f3n y siendo la ARS p\u00fablica, la \u00fanica en contar con certificaci\u00f3n de calidad internacional ISO 9001:2015, as\u00ed como el reconocimiento en Iberoam\u00e9rica con medalla de plata en el Premio Iberoamericano a la calidad.<\/p>\n\n\n\n<p><strong>Antecedentes<\/strong><\/p>\n\n\n\n<p>Se recuerda que la segunda semana de este mes, el Tribunal Constitucional (TC) declar\u00f3 inadmisible el recurso de amparo incoado por seis Administradoras de Riesgos de Salud (ARS) que se oponen a que los empleados p\u00fablicos, aut\u00f3nomos y descentralizados sean afiliados al SeNaSa, tal como plantea la Ley No. 87-01 que crea el sistema.<\/p>\n\n\n\n<p style=\"text-align:right\"><strong>Gerencia de Comunicaci\u00f3n Estrat\u00e9gica. Lunes 28 de enero de 2019<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>SeNaSa est\u00e1 m\u00e1s que lista para recibir a los empleados p\u00fablicos. La ARS estatal explica no hace falta una sentencia para que los empleados p\u00fablicos sean afiliados a ella, ya que la Ley No. 87-01, en su art\u00edculo 31, as\u00ed lo establece. Santo Domingo-. El Seguro Nacional de Salud (SeNaSa) explic\u00f3 que el traspaso de [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":1623,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"yasr_overall_rating":0,"yasr_post_is_review":"","yasr_auto_insert_disabled":"","yasr_review_type":"","_glsr_average":0,"_glsr_ranking":0,"_glsr_reviews":0,"footnotes":""},"categories":[13],"tags":[],"class_list":["post-1622","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El paso de los empleados p\u00fablicos a SeNaSa es constitucional; SeNaSa reafirma est\u00e1 m\u00e1s que lista para recibirlos - ARSSeNaSa<\/title>\n<meta name=\"description\" content=\"%\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.arssenasa.gob.do\/index.php\/blog\/2019\/01\/28\/el-paso-de-los-empleados-publicos-a-senasa-es-constitucional-senasa-reafirma-esta-mas-que-lista-para-recibirlos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El paso de los empleados p\u00fablicos a SeNaSa es constitucional; SeNaSa reafirma est\u00e1 m\u00e1s que lista para recibirlos - ARSSeNaSa\" \/>\n<meta property=\"og:description\" content=\"%\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.arssenasa.gob.do\/index.php\/blog\/2019\/01\/28\/el-paso-de-los-empleados-publicos-a-senasa-es-constitucional-senasa-reafirma-esta-mas-que-lista-para-recibirlos\/\" \/>\n<meta property=\"og:site_name\" content=\"ARSSeNaSa\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ARSSeNaSaRD\" \/>\n<meta property=\"article:published_time\" content=\"2019-01-28T20:35:58+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-03-19T15:06:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.arssenasa.gob.do\/wp-content\/uploads\/2019\/01\/Edificio-SeNaSa.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"683\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"SeNaSa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@arssenasard\" \/>\n<meta name=\"twitter:site\" content=\"@arssenasard\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"SeNaSa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.arssenasa.gob.do\/index.php\/blog\/2019\/01\/28\/el-paso-de-los-empleados-publicos-a-senasa-es-constitucional-senasa-reafirma-esta-mas-que-lista-para-recibirlos\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.arssenasa.gob.do\/index.php\/blog\/2019\/01\/28\/el-paso-de-los-empleados-publicos-a-senasa-es-constitucional-senasa-reafirma-esta-mas-que-lista-para-recibirlos\/\"},\"author\":{\"name\":\"SeNaSa\",\"@id\":\"https:\/\/www.arssenasa.gob.do\/#\/schema\/person\/b9d6c2c58f44cdecdcdaab7a6f9504c0\"},\"headline\":\"El paso de los empleados p\u00fablicos a SeNaSa es constitucional; SeNaSa reafirma est\u00e1 m\u00e1s que lista para recibirlos\",\"datePublished\":\"2019-01-28T20:35:58+00:00\",\"dateModified\":\"2019-03-19T15:06:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.arssenasa.gob.do\/index.php\/blog\/2019\/01\/28\/el-paso-de-los-empleados-publicos-a-senasa-es-constitucional-senasa-reafirma-esta-mas-que-lista-para-recibirlos\/\"},\"wordCount\":496,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.arssenasa.gob.do\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.arssenasa.gob.do\/index.php\/blog\/2019\/01\/28\/el-paso-de-los-empleados-publicos-a-senasa-es-constitucional-senasa-reafirma-esta-mas-que-lista-para-recibirlos\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.arssenasa.gob.do\/wp-content\/uploads\/2019\/01\/Edificio-SeNaSa.jpeg\",\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.arssenasa.gob.do\/index.php\/blog\/2019\/01\/28\/el-paso-de-los-empleados-publicos-a-senasa-es-constitucional-senasa-reafirma-esta-mas-que-lista-para-recibirlos\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.arssenasa.gob.do\/index.php\/blog\/2019\/01\/28\/el-paso-de-los-empleados-publicos-a-senasa-es-constitucional-senasa-reafirma-esta-mas-que-lista-para-recibirlos\/\",\"url\":\"https:\/\/www.arssenasa.gob.do\/index.php\/blog\/2019\/01\/28\/el-paso-de-los-empleados-publicos-a-senasa-es-constitucional-senasa-reafirma-esta-mas-que-lista-para-recibirlos\/\",\"name\":\"El paso de los empleados p\u00fablicos a SeNaSa es constitucional; SeNaSa reafirma est\u00e1 m\u00e1s que lista para recibirlos - ARSSeNaSa\",\"isPartOf\":{\"@id\":\"https:\/\/www.arssenasa.gob.do\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.arssenasa.gob.do\/index.php\/blog\/2019\/01\/28\/el-paso-de-los-empleados-publicos-a-senasa-es-constitucional-senasa-reafirma-esta-mas-que-lista-para-recibirlos\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.arssenasa.gob.do\/index.php\/blog\/2019\/01\/28\/el-paso-de-los-empleados-publicos-a-senasa-es-constitucional-senasa-reafirma-esta-mas-que-lista-para-recibirlos\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.arssenasa.gob.do\/wp-content\/uploads\/2019\/01\/Edificio-SeNaSa.jpeg\",\"datePublished\":\"2019-01-28T20:35:58+00:00\",\"dateModified\":\"2019-03-19T15:06:02+00:00\",\"description\":\"%\",\"breadcrumb\":{\"@id\":\"https:\/\/www.arssenasa.gob.do\/index.php\/blog\/2019\/01\/28\/el-paso-de-los-empleados-publicos-a-senasa-es-constitucional-senasa-reafirma-esta-mas-que-lista-para-recibirlos\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.arssenasa.gob.do\/index.php\/blog\/2019\/01\/28\/el-paso-de-los-empleados-publicos-a-senasa-es-constitucional-senasa-reafirma-esta-mas-que-lista-para-recibirlos\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.arssenasa.gob.do\/index.php\/blog\/2019\/01\/28\/el-paso-de-los-empleados-publicos-a-senasa-es-constitucional-senasa-reafirma-esta-mas-que-lista-para-recibirlos\/#primaryimage\",\"url\":\"https:\/\/www.arssenasa.gob.do\/wp-content\/uploads\/2019\/01\/Edificio-SeNaSa.jpeg\",\"contentUrl\":\"https:\/\/www.arssenasa.gob.do\/wp-content\/uploads\/2019\/01\/Edificio-SeNaSa.jpeg\",\"width\":1024,\"height\":683,\"caption\":\"Fachada Senasa\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.arssenasa.gob.do\/index.php\/blog\/2019\/01\/28\/el-paso-de-los-empleados-publicos-a-senasa-es-constitucional-senasa-reafirma-esta-mas-que-lista-para-recibirlos\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\/\/www.arssenasa.gob.do\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El paso de los empleados p\u00fablicos a SeNaSa es constitucional; SeNaSa reafirma est\u00e1 m\u00e1s que lista para recibirlos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.arssenasa.gob.do\/#website\",\"url\":\"https:\/\/www.arssenasa.gob.do\/\",\"name\":\"ARSSeNaSa\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.arssenasa.gob.do\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.arssenasa.gob.do\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.arssenasa.gob.do\/#organization\",\"name\":\"SeNaSa - Seguro Nacional de Salud\",\"url\":\"https:\/\/www.arssenasa.gob.do\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.arssenasa.gob.do\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.arssenasa.gob.do\/wp-content\/uploads\/2018\/11\/logo2022.png\",\"contentUrl\":\"https:\/\/www.arssenasa.gob.do\/wp-content\/uploads\/2018\/11\/logo2022.png\",\"width\":310,\"height\":200,\"caption\":\"SeNaSa - Seguro Nacional de Salud\"},\"image\":{\"@id\":\"https:\/\/www.arssenasa.gob.do\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/ARSSeNaSaRD\",\"https:\/\/x.com\/arssenasard\",\"https:\/\/www.instagram.com\/arssenasard\/\",\"https:\/\/www.youtube.com\/user\/ARSSeNaSa\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.arssenasa.gob.do\/#\/schema\/person\/b9d6c2c58f44cdecdcdaab7a6f9504c0\",\"name\":\"SeNaSa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.arssenasa.gob.do\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/3c45125f46520136bb5577344179f8312f2704a1174137df27ae1baa182b5a6e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/3c45125f46520136bb5577344179f8312f2704a1174137df27ae1baa182b5a6e?s=96&d=mm&r=g\",\"caption\":\"SeNaSa\"},\"url\":\"https:\/\/www.arssenasa.gob.do\/index.php\/blog\/author\/admin\/\"},false]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El paso de los empleados p\u00fablicos a SeNaSa es constitucional; SeNaSa reafirma est\u00e1 m\u00e1s que lista para recibirlos - ARSSeNaSa","description":"%","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.arssenasa.gob.do\/index.php\/blog\/2019\/01\/28\/el-paso-de-los-empleados-publicos-a-senasa-es-constitucional-senasa-reafirma-esta-mas-que-lista-para-recibirlos\/","og_locale":"es_ES","og_type":"article","og_title":"El paso de los empleados p\u00fablicos a SeNaSa es constitucional; SeNaSa reafirma est\u00e1 m\u00e1s que lista para recibirlos - ARSSeNaSa","og_description":"%","og_url":"https:\/\/www.arssenasa.gob.do\/index.php\/blog\/2019\/01\/28\/el-paso-de-los-empleados-publicos-a-senasa-es-constitucional-senasa-reafirma-esta-mas-que-lista-para-recibirlos\/","og_site_name":"ARSSeNaSa","article_publisher":"https:\/\/www.facebook.com\/ARSSeNaSaRD","article_published_time":"2019-01-28T20:35:58+00:00","article_modified_time":"2019-03-19T15:06:02+00:00","og_image":[{"width":1024,"height":683,"url":"https:\/\/www.arssenasa.gob.do\/wp-content\/uploads\/2019\/01\/Edificio-SeNaSa.jpeg","type":"image\/jpeg"}],"author":"SeNaSa","twitter_card":"summary_large_image","twitter_creator":"@arssenasard","twitter_site":"@arssenasard","twitter_misc":{"Written by":"SeNaSa","Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.arssenasa.gob.do\/index.php\/blog\/2019\/01\/28\/el-paso-de-los-empleados-publicos-a-senasa-es-constitucional-senasa-reafirma-esta-mas-que-lista-para-recibirlos\/#article","isPartOf":{"@id":"https:\/\/www.arssenasa.gob.do\/index.php\/blog\/2019\/01\/28\/el-paso-de-los-empleados-publicos-a-senasa-es-constitucional-senasa-reafirma-esta-mas-que-lista-para-recibirlos\/"},"author":{"name":"SeNaSa","@id":"https:\/\/www.arssenasa.gob.do\/#\/schema\/person\/b9d6c2c58f44cdecdcdaab7a6f9504c0"},"headline":"El paso de los empleados p\u00fablicos a SeNaSa es constitucional; SeNaSa reafirma est\u00e1 m\u00e1s que lista para recibirlos","datePublished":"2019-01-28T20:35:58+00:00","dateModified":"2019-03-19T15:06:02+00:00","mainEntityOfPage":{"@id":"https:\/\/www.arssenasa.gob.do\/index.php\/blog\/2019\/01\/28\/el-paso-de-los-empleados-publicos-a-senasa-es-constitucional-senasa-reafirma-esta-mas-que-lista-para-recibirlos\/"},"wordCount":496,"commentCount":0,"publisher":{"@id":"https:\/\/www.arssenasa.gob.do\/#organization"},"image":{"@id":"https:\/\/www.arssenasa.gob.do\/index.php\/blog\/2019\/01\/28\/el-paso-de-los-empleados-publicos-a-senasa-es-constitucional-senasa-reafirma-esta-mas-que-lista-para-recibirlos\/#primaryimage"},"thumbnailUrl":"https:\/\/www.arssenasa.gob.do\/wp-content\/uploads\/2019\/01\/Edificio-SeNaSa.jpeg","articleSection":["Noticias"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.arssenasa.gob.do\/index.php\/blog\/2019\/01\/28\/el-paso-de-los-empleados-publicos-a-senasa-es-constitucional-senasa-reafirma-esta-mas-que-lista-para-recibirlos\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.arssenasa.gob.do\/index.php\/blog\/2019\/01\/28\/el-paso-de-los-empleados-publicos-a-senasa-es-constitucional-senasa-reafirma-esta-mas-que-lista-para-recibirlos\/","url":"https:\/\/www.arssenasa.gob.do\/index.php\/blog\/2019\/01\/28\/el-paso-de-los-empleados-publicos-a-senasa-es-constitucional-senasa-reafirma-esta-mas-que-lista-para-recibirlos\/","name":"El paso de los empleados p\u00fablicos a SeNaSa es constitucional; SeNaSa reafirma est\u00e1 m\u00e1s que lista para recibirlos - ARSSeNaSa","isPartOf":{"@id":"https:\/\/www.arssenasa.gob.do\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.arssenasa.gob.do\/index.php\/blog\/2019\/01\/28\/el-paso-de-los-empleados-publicos-a-senasa-es-constitucional-senasa-reafirma-esta-mas-que-lista-para-recibirlos\/#primaryimage"},"image":{"@id":"https:\/\/www.arssenasa.gob.do\/index.php\/blog\/2019\/01\/28\/el-paso-de-los-empleados-publicos-a-senasa-es-constitucional-senasa-reafirma-esta-mas-que-lista-para-recibirlos\/#primaryimage"},"thumbnailUrl":"https:\/\/www.arssenasa.gob.do\/wp-content\/uploads\/2019\/01\/Edificio-SeNaSa.jpeg","datePublished":"2019-01-28T20:35:58+00:00","dateModified":"2019-03-19T15:06:02+00:00","description":"%","breadcrumb":{"@id":"https:\/\/www.arssenasa.gob.do\/index.php\/blog\/2019\/01\/28\/el-paso-de-los-empleados-publicos-a-senasa-es-constitucional-senasa-reafirma-esta-mas-que-lista-para-recibirlos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.arssenasa.gob.do\/index.php\/blog\/2019\/01\/28\/el-paso-de-los-empleados-publicos-a-senasa-es-constitucional-senasa-reafirma-esta-mas-que-lista-para-recibirlos\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.arssenasa.gob.do\/index.php\/blog\/2019\/01\/28\/el-paso-de-los-empleados-publicos-a-senasa-es-constitucional-senasa-reafirma-esta-mas-que-lista-para-recibirlos\/#primaryimage","url":"https:\/\/www.arssenasa.gob.do\/wp-content\/uploads\/2019\/01\/Edificio-SeNaSa.jpeg","contentUrl":"https:\/\/www.arssenasa.gob.do\/wp-content\/uploads\/2019\/01\/Edificio-SeNaSa.jpeg","width":1024,"height":683,"caption":"Fachada Senasa"},{"@type":"BreadcrumbList","@id":"https:\/\/www.arssenasa.gob.do\/index.php\/blog\/2019\/01\/28\/el-paso-de-los-empleados-publicos-a-senasa-es-constitucional-senasa-reafirma-esta-mas-que-lista-para-recibirlos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.arssenasa.gob.do\/"},{"@type":"ListItem","position":2,"name":"El paso de los empleados p\u00fablicos a SeNaSa es constitucional; SeNaSa reafirma est\u00e1 m\u00e1s que lista para recibirlos"}]},{"@type":"WebSite","@id":"https:\/\/www.arssenasa.gob.do\/#website","url":"https:\/\/www.arssenasa.gob.do\/","name":"ARSSeNaSa","description":"","publisher":{"@id":"https:\/\/www.arssenasa.gob.do\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.arssenasa.gob.do\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.arssenasa.gob.do\/#organization","name":"SeNaSa - Seguro Nacional de Salud","url":"https:\/\/www.arssenasa.gob.do\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.arssenasa.gob.do\/#\/schema\/logo\/image\/","url":"https:\/\/www.arssenasa.gob.do\/wp-content\/uploads\/2018\/11\/logo2022.png","contentUrl":"https:\/\/www.arssenasa.gob.do\/wp-content\/uploads\/2018\/11\/logo2022.png","width":310,"height":200,"caption":"SeNaSa - Seguro Nacional de Salud"},"image":{"@id":"https:\/\/www.arssenasa.gob.do\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ARSSeNaSaRD","https:\/\/x.com\/arssenasard","https:\/\/www.instagram.com\/arssenasard\/","https:\/\/www.youtube.com\/user\/ARSSeNaSa"]},{"@type":"Person","@id":"https:\/\/www.arssenasa.gob.do\/#\/schema\/person\/b9d6c2c58f44cdecdcdaab7a6f9504c0","name":"SeNaSa","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.arssenasa.gob.do\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/3c45125f46520136bb5577344179f8312f2704a1174137df27ae1baa182b5a6e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3c45125f46520136bb5577344179f8312f2704a1174137df27ae1baa182b5a6e?s=96&d=mm&r=g","caption":"SeNaSa"},"url":"https:\/\/www.arssenasa.gob.do\/index.php\/blog\/author\/admin\/"},false]}},"yasr_visitor_votes":{"stars_attributes":{"read_only":false,"span_bottom":false},"number_of_votes":0,"sum_votes":0},"_links":{"self":[{"href":"https:\/\/www.arssenasa.gob.do\/index.php\/wp-json\/wp\/v2\/posts\/1622","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.arssenasa.gob.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.arssenasa.gob.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.arssenasa.gob.do\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.arssenasa.gob.do\/index.php\/wp-json\/wp\/v2\/comments?post=1622"}],"version-history":[{"count":0,"href":"https:\/\/www.arssenasa.gob.do\/index.php\/wp-json\/wp\/v2\/posts\/1622\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.arssenasa.gob.do\/index.php\/wp-json\/wp\/v2\/media\/1623"}],"wp:attachment":[{"href":"https:\/\/www.arssenasa.gob.do\/index.php\/wp-json\/wp\/v2\/media?parent=1622"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.arssenasa.gob.do\/index.php\/wp-json\/wp\/v2\/categories?post=1622"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.arssenasa.gob.do\/index.php\/wp-json\/wp\/v2\/tags?post=1622"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}