{"id":1630,"date":"2019-02-05T16:46:39","date_gmt":"2019-02-05T20:46:39","guid":{"rendered":"http:\/\/192.168.1.138\/wordpress\/?p=1630"},"modified":"2019-02-05T16:46:43","modified_gmt":"2019-02-05T20:46:43","slug":"senasa-reitera-no-hace-falta-sentencia-para-afiliarse-invita-a-empleados-publicos-a-traspasarse","status":"publish","type":"post","link":"https:\/\/www.arssenasa.gob.do\/index.php\/blog\/2019\/02\/05\/senasa-reitera-no-hace-falta-sentencia-para-afiliarse-invita-a-empleados-publicos-a-traspasarse\/","title":{"rendered":"SeNaSa reitera no hace falta sentencia para afiliarse; invita a empleados p\u00fablicos a traspasarse"},"content":{"rendered":"\n<p style=\"text-align:center\"><em>Los\nafiliados al R\u00e9gimen Contributivo cuentan con la red m\u00e1s amplia de Prestadores\nde Servicios de Salud (PSS) privados en todo el pa\u00eds<\/em><\/p>\n\n\n\n<p><strong>Santo Domingo. &#8211;<\/strong> El Seguro Nacional de Salud (SeNaSa) reiter\u00f3\nque no hace falta una sentencia para que los empleados p\u00fablicos est\u00e9n afiliados\na la ARS estatal, ya que la Ley 87-01 en su art\u00edculo 31 lo establece, al tiempo\nque invit\u00f3 a los empleados p\u00fablicos a afiliarse a la ARS del Estado, donde se\nles van a garantizar todos sus derechos.<\/p>\n\n\n\n<p>\u201cLo\nm\u00e1s importante que tenemos en SeNaSa es que no perseguimos lucro, porque\nnuestro principal enfoque es garantizar los derechos de cada uno de nuestros\nafiliados\u201d, expres\u00f3 la directora ejecutiva de SeNaSa, doctora Mercedes\nRodr\u00edguez Silver.<\/p>\n\n\n\n<p><strong>Red de prestadores m\u00e1s amplia<\/strong><\/p>\n\n\n\n<p>La\ndoctora Rodr\u00edguez Silver precis\u00f3 que SeNaSa cuenta con m\u00e1s de 8,000 Prestadores\nde Servicios de Salud (PSS) privados distribuidos a nivel nacional, lo que se garantiza\na los afiliados un mayor acceso a los servicios de salud. <\/p>\n\n\n\n<p>Indic\u00f3\nque cualquier empleado p\u00fablico o privado puede entrar a SeNaSa en el R\u00e9gimen\nContributivo, donde actualmente contamos con m\u00e1s de un mill\u00f3n de afiliados que han\nelegido libremente a la ARS estatal como su seguro de salud.<\/p>\n\n\n\n<p><strong>Planes complementarios<\/strong><\/p>\n\n\n\n<p>SeNaSa\ncuenta con planes complementarios que tienen la Red de Prestadores de Servicios\nde Salud del R\u00e9gimen Contributivo y adicional cuenta con una Red Premium con\notras cl\u00ednicas y centros m\u00e9dicos privados.<\/p>\n\n\n\n<p>Estos\nplanes ofrecen 614 procedimientos adicionales al Plan Servicios de Salud (PDSS\n3.0), eliminando el pago de diferencias en diversas coberturas, logrando con\nesto una combinaci\u00f3n de confort y mayor beneficio para los afiliados. <\/p>\n\n\n\n<p>Actualmente\nSeNaSa cuenta con 4 planes complementarios, que son: SeNaSa Especial, SeNaSa\nAvanzado, SeNaSa M\u00e1ximo y SeNaSa Premium, adem\u00e1s, planes opcionales. <\/p>\n\n\n\n<p><strong>Cartera de afiliados <\/strong><\/p>\n\n\n\n<p>Rodr\u00edguez\nSilver destac\u00f3 que la cartera de afiliados del R\u00e9gimen Contributivo est\u00e1\ncompuesta por un 70% de empleados p\u00fablicos y un 30% de empleados privados.<\/p>\n\n\n\n<p>Explic\u00f3\nque SeNaSa, adem\u00e1s, exhibe altos est\u00e1ndares de calidad y se posiciona como la\n\u00fanica ARS en contar con la certificaci\u00f3n internacional de calidad ISO\n9001:2015, y cuenta con el\nAPP SeNaSa, la cual permite a los afiliados tener todas las informaciones y\nnovedades donde se encuentren.&nbsp;&nbsp; <\/p>\n\n\n\n<p><strong>Requisitos para el traspaso<\/strong><\/p>\n\n\n\n<p>Conforme a lo establecido por la\nSuperintendencia de Salud y Riesgos Laborales (SISALRIL), los requisitos para\nque un empleado pueda traspasarse de una ARS a otra son: tener doce meses\ncotizando de manera consecutiva en la ARS actual, no tener ninguna cirug\u00eda\nelectiva pendiente ni enfermedades de alto costo.<\/p>\n\n\n\n<p>Durante el per\u00edodo de traspaso el afiliado nunca queda desprotegido, sino que la ARS en la que est\u00e1 actualmente se mantiene dando cobertura hasta que entre a la otra ARS que escogi\u00f3.<\/p>\n\n\n\n<p style=\"text-align:right\"><strong>Gerencia de Comunicaci\u00f3n Estrat\u00e9gica. <br> Martes 05 de febrero de 2019.-<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los afiliados al R\u00e9gimen Contributivo cuentan con la red m\u00e1s amplia de Prestadores de Servicios de Salud (PSS) privados en todo el pa\u00eds Santo Domingo. &#8211; El Seguro Nacional de Salud (SeNaSa) reiter\u00f3 que no hace falta una sentencia para que los empleados p\u00fablicos est\u00e9n afiliados a la ARS estatal, ya que la Ley 87-01 [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":1631,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"yasr_overall_rating":0,"yasr_post_is_review":"","yasr_auto_insert_disabled":"","yasr_review_type":"","_glsr_average":0,"_glsr_ranking":0,"_glsr_reviews":0,"footnotes":""},"categories":[13],"tags":[],"class_list":["post-1630","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>SeNaSa reitera no hace falta sentencia para afiliarse; invita a empleados p\u00fablicos a traspasarse - ARSSeNaSa<\/title>\n<meta name=\"description\" content=\"%\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.arssenasa.gob.do\/index.php\/blog\/2019\/02\/05\/senasa-reitera-no-hace-falta-sentencia-para-afiliarse-invita-a-empleados-publicos-a-traspasarse\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"SeNaSa reitera no hace falta sentencia para afiliarse; invita a empleados p\u00fablicos a traspasarse - ARSSeNaSa\" \/>\n<meta property=\"og:description\" content=\"%\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.arssenasa.gob.do\/index.php\/blog\/2019\/02\/05\/senasa-reitera-no-hace-falta-sentencia-para-afiliarse-invita-a-empleados-publicos-a-traspasarse\/\" \/>\n<meta property=\"og:site_name\" content=\"ARSSeNaSa\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ARSSeNaSaRD\" \/>\n<meta property=\"article:published_time\" content=\"2019-02-05T20:46:39+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-02-05T20:46:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.arssenasa.gob.do\/wp-content\/uploads\/2019\/02\/SeNaSa.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1325\" \/>\n\t<meta property=\"og:image:height\" content=\"409\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"SeNaSa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@arssenasard\" \/>\n<meta name=\"twitter:site\" content=\"@arssenasard\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"SeNaSa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.arssenasa.gob.do\/index.php\/blog\/2019\/02\/05\/senasa-reitera-no-hace-falta-sentencia-para-afiliarse-invita-a-empleados-publicos-a-traspasarse\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.arssenasa.gob.do\/index.php\/blog\/2019\/02\/05\/senasa-reitera-no-hace-falta-sentencia-para-afiliarse-invita-a-empleados-publicos-a-traspasarse\/\"},\"author\":{\"name\":\"SeNaSa\",\"@id\":\"https:\/\/www.arssenasa.gob.do\/#\/schema\/person\/b9d6c2c58f44cdecdcdaab7a6f9504c0\"},\"headline\":\"SeNaSa reitera no hace falta sentencia para afiliarse; invita a empleados p\u00fablicos a traspasarse\",\"datePublished\":\"2019-02-05T20:46:39+00:00\",\"dateModified\":\"2019-02-05T20:46:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.arssenasa.gob.do\/index.php\/blog\/2019\/02\/05\/senasa-reitera-no-hace-falta-sentencia-para-afiliarse-invita-a-empleados-publicos-a-traspasarse\/\"},\"wordCount\":500,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.arssenasa.gob.do\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.arssenasa.gob.do\/index.php\/blog\/2019\/02\/05\/senasa-reitera-no-hace-falta-sentencia-para-afiliarse-invita-a-empleados-publicos-a-traspasarse\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.arssenasa.gob.do\/wp-content\/uploads\/2019\/02\/SeNaSa.jpg\",\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.arssenasa.gob.do\/index.php\/blog\/2019\/02\/05\/senasa-reitera-no-hace-falta-sentencia-para-afiliarse-invita-a-empleados-publicos-a-traspasarse\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.arssenasa.gob.do\/index.php\/blog\/2019\/02\/05\/senasa-reitera-no-hace-falta-sentencia-para-afiliarse-invita-a-empleados-publicos-a-traspasarse\/\",\"url\":\"https:\/\/www.arssenasa.gob.do\/index.php\/blog\/2019\/02\/05\/senasa-reitera-no-hace-falta-sentencia-para-afiliarse-invita-a-empleados-publicos-a-traspasarse\/\",\"name\":\"SeNaSa reitera no hace falta sentencia para afiliarse; invita a empleados p\u00fablicos a traspasarse - ARSSeNaSa\",\"isPartOf\":{\"@id\":\"https:\/\/www.arssenasa.gob.do\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.arssenasa.gob.do\/index.php\/blog\/2019\/02\/05\/senasa-reitera-no-hace-falta-sentencia-para-afiliarse-invita-a-empleados-publicos-a-traspasarse\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.arssenasa.gob.do\/index.php\/blog\/2019\/02\/05\/senasa-reitera-no-hace-falta-sentencia-para-afiliarse-invita-a-empleados-publicos-a-traspasarse\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.arssenasa.gob.do\/wp-content\/uploads\/2019\/02\/SeNaSa.jpg\",\"datePublished\":\"2019-02-05T20:46:39+00:00\",\"dateModified\":\"2019-02-05T20:46:43+00:00\",\"description\":\"%\",\"breadcrumb\":{\"@id\":\"https:\/\/www.arssenasa.gob.do\/index.php\/blog\/2019\/02\/05\/senasa-reitera-no-hace-falta-sentencia-para-afiliarse-invita-a-empleados-publicos-a-traspasarse\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.arssenasa.gob.do\/index.php\/blog\/2019\/02\/05\/senasa-reitera-no-hace-falta-sentencia-para-afiliarse-invita-a-empleados-publicos-a-traspasarse\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.arssenasa.gob.do\/index.php\/blog\/2019\/02\/05\/senasa-reitera-no-hace-falta-sentencia-para-afiliarse-invita-a-empleados-publicos-a-traspasarse\/#primaryimage\",\"url\":\"https:\/\/www.arssenasa.gob.do\/wp-content\/uploads\/2019\/02\/SeNaSa.jpg\",\"contentUrl\":\"https:\/\/www.arssenasa.gob.do\/wp-content\/uploads\/2019\/02\/SeNaSa.jpg\",\"width\":1325,\"height\":409,\"caption\":\"Centro de Atenci\u00f3n al Usuario\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.arssenasa.gob.do\/index.php\/blog\/2019\/02\/05\/senasa-reitera-no-hace-falta-sentencia-para-afiliarse-invita-a-empleados-publicos-a-traspasarse\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\/\/www.arssenasa.gob.do\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"SeNaSa reitera no hace falta sentencia para afiliarse; invita a empleados p\u00fablicos a traspasarse\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.arssenasa.gob.do\/#website\",\"url\":\"https:\/\/www.arssenasa.gob.do\/\",\"name\":\"ARSSeNaSa\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.arssenasa.gob.do\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.arssenasa.gob.do\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.arssenasa.gob.do\/#organization\",\"name\":\"SeNaSa - Seguro Nacional de Salud\",\"url\":\"https:\/\/www.arssenasa.gob.do\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.arssenasa.gob.do\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.arssenasa.gob.do\/wp-content\/uploads\/2018\/11\/logo2022.png\",\"contentUrl\":\"https:\/\/www.arssenasa.gob.do\/wp-content\/uploads\/2018\/11\/logo2022.png\",\"width\":310,\"height\":200,\"caption\":\"SeNaSa - Seguro Nacional de Salud\"},\"image\":{\"@id\":\"https:\/\/www.arssenasa.gob.do\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/ARSSeNaSaRD\",\"https:\/\/x.com\/arssenasard\",\"https:\/\/www.instagram.com\/arssenasard\/\",\"https:\/\/www.youtube.com\/user\/ARSSeNaSa\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.arssenasa.gob.do\/#\/schema\/person\/b9d6c2c58f44cdecdcdaab7a6f9504c0\",\"name\":\"SeNaSa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.arssenasa.gob.do\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/3c45125f46520136bb5577344179f8312f2704a1174137df27ae1baa182b5a6e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/3c45125f46520136bb5577344179f8312f2704a1174137df27ae1baa182b5a6e?s=96&d=mm&r=g\",\"caption\":\"SeNaSa\"},\"url\":\"https:\/\/www.arssenasa.gob.do\/index.php\/blog\/author\/admin\/\"},false]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"SeNaSa reitera no hace falta sentencia para afiliarse; invita a empleados p\u00fablicos a traspasarse - ARSSeNaSa","description":"%","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.arssenasa.gob.do\/index.php\/blog\/2019\/02\/05\/senasa-reitera-no-hace-falta-sentencia-para-afiliarse-invita-a-empleados-publicos-a-traspasarse\/","og_locale":"es_ES","og_type":"article","og_title":"SeNaSa reitera no hace falta sentencia para afiliarse; invita a empleados p\u00fablicos a traspasarse - ARSSeNaSa","og_description":"%","og_url":"https:\/\/www.arssenasa.gob.do\/index.php\/blog\/2019\/02\/05\/senasa-reitera-no-hace-falta-sentencia-para-afiliarse-invita-a-empleados-publicos-a-traspasarse\/","og_site_name":"ARSSeNaSa","article_publisher":"https:\/\/www.facebook.com\/ARSSeNaSaRD","article_published_time":"2019-02-05T20:46:39+00:00","article_modified_time":"2019-02-05T20:46:43+00:00","og_image":[{"width":1325,"height":409,"url":"https:\/\/www.arssenasa.gob.do\/wp-content\/uploads\/2019\/02\/SeNaSa.jpg","type":"image\/jpeg"}],"author":"SeNaSa","twitter_card":"summary_large_image","twitter_creator":"@arssenasard","twitter_site":"@arssenasard","twitter_misc":{"Written by":"SeNaSa","Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.arssenasa.gob.do\/index.php\/blog\/2019\/02\/05\/senasa-reitera-no-hace-falta-sentencia-para-afiliarse-invita-a-empleados-publicos-a-traspasarse\/#article","isPartOf":{"@id":"https:\/\/www.arssenasa.gob.do\/index.php\/blog\/2019\/02\/05\/senasa-reitera-no-hace-falta-sentencia-para-afiliarse-invita-a-empleados-publicos-a-traspasarse\/"},"author":{"name":"SeNaSa","@id":"https:\/\/www.arssenasa.gob.do\/#\/schema\/person\/b9d6c2c58f44cdecdcdaab7a6f9504c0"},"headline":"SeNaSa reitera no hace falta sentencia para afiliarse; invita a empleados p\u00fablicos a traspasarse","datePublished":"2019-02-05T20:46:39+00:00","dateModified":"2019-02-05T20:46:43+00:00","mainEntityOfPage":{"@id":"https:\/\/www.arssenasa.gob.do\/index.php\/blog\/2019\/02\/05\/senasa-reitera-no-hace-falta-sentencia-para-afiliarse-invita-a-empleados-publicos-a-traspasarse\/"},"wordCount":500,"commentCount":0,"publisher":{"@id":"https:\/\/www.arssenasa.gob.do\/#organization"},"image":{"@id":"https:\/\/www.arssenasa.gob.do\/index.php\/blog\/2019\/02\/05\/senasa-reitera-no-hace-falta-sentencia-para-afiliarse-invita-a-empleados-publicos-a-traspasarse\/#primaryimage"},"thumbnailUrl":"https:\/\/www.arssenasa.gob.do\/wp-content\/uploads\/2019\/02\/SeNaSa.jpg","articleSection":["Noticias"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.arssenasa.gob.do\/index.php\/blog\/2019\/02\/05\/senasa-reitera-no-hace-falta-sentencia-para-afiliarse-invita-a-empleados-publicos-a-traspasarse\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.arssenasa.gob.do\/index.php\/blog\/2019\/02\/05\/senasa-reitera-no-hace-falta-sentencia-para-afiliarse-invita-a-empleados-publicos-a-traspasarse\/","url":"https:\/\/www.arssenasa.gob.do\/index.php\/blog\/2019\/02\/05\/senasa-reitera-no-hace-falta-sentencia-para-afiliarse-invita-a-empleados-publicos-a-traspasarse\/","name":"SeNaSa reitera no hace falta sentencia para afiliarse; invita a empleados p\u00fablicos a traspasarse - ARSSeNaSa","isPartOf":{"@id":"https:\/\/www.arssenasa.gob.do\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.arssenasa.gob.do\/index.php\/blog\/2019\/02\/05\/senasa-reitera-no-hace-falta-sentencia-para-afiliarse-invita-a-empleados-publicos-a-traspasarse\/#primaryimage"},"image":{"@id":"https:\/\/www.arssenasa.gob.do\/index.php\/blog\/2019\/02\/05\/senasa-reitera-no-hace-falta-sentencia-para-afiliarse-invita-a-empleados-publicos-a-traspasarse\/#primaryimage"},"thumbnailUrl":"https:\/\/www.arssenasa.gob.do\/wp-content\/uploads\/2019\/02\/SeNaSa.jpg","datePublished":"2019-02-05T20:46:39+00:00","dateModified":"2019-02-05T20:46:43+00:00","description":"%","breadcrumb":{"@id":"https:\/\/www.arssenasa.gob.do\/index.php\/blog\/2019\/02\/05\/senasa-reitera-no-hace-falta-sentencia-para-afiliarse-invita-a-empleados-publicos-a-traspasarse\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.arssenasa.gob.do\/index.php\/blog\/2019\/02\/05\/senasa-reitera-no-hace-falta-sentencia-para-afiliarse-invita-a-empleados-publicos-a-traspasarse\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.arssenasa.gob.do\/index.php\/blog\/2019\/02\/05\/senasa-reitera-no-hace-falta-sentencia-para-afiliarse-invita-a-empleados-publicos-a-traspasarse\/#primaryimage","url":"https:\/\/www.arssenasa.gob.do\/wp-content\/uploads\/2019\/02\/SeNaSa.jpg","contentUrl":"https:\/\/www.arssenasa.gob.do\/wp-content\/uploads\/2019\/02\/SeNaSa.jpg","width":1325,"height":409,"caption":"Centro de Atenci\u00f3n al Usuario"},{"@type":"BreadcrumbList","@id":"https:\/\/www.arssenasa.gob.do\/index.php\/blog\/2019\/02\/05\/senasa-reitera-no-hace-falta-sentencia-para-afiliarse-invita-a-empleados-publicos-a-traspasarse\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.arssenasa.gob.do\/"},{"@type":"ListItem","position":2,"name":"SeNaSa reitera no hace falta sentencia para afiliarse; invita a empleados p\u00fablicos a traspasarse"}]},{"@type":"WebSite","@id":"https:\/\/www.arssenasa.gob.do\/#website","url":"https:\/\/www.arssenasa.gob.do\/","name":"ARSSeNaSa","description":"","publisher":{"@id":"https:\/\/www.arssenasa.gob.do\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.arssenasa.gob.do\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.arssenasa.gob.do\/#organization","name":"SeNaSa - Seguro Nacional de Salud","url":"https:\/\/www.arssenasa.gob.do\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.arssenasa.gob.do\/#\/schema\/logo\/image\/","url":"https:\/\/www.arssenasa.gob.do\/wp-content\/uploads\/2018\/11\/logo2022.png","contentUrl":"https:\/\/www.arssenasa.gob.do\/wp-content\/uploads\/2018\/11\/logo2022.png","width":310,"height":200,"caption":"SeNaSa - Seguro Nacional de Salud"},"image":{"@id":"https:\/\/www.arssenasa.gob.do\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ARSSeNaSaRD","https:\/\/x.com\/arssenasard","https:\/\/www.instagram.com\/arssenasard\/","https:\/\/www.youtube.com\/user\/ARSSeNaSa"]},{"@type":"Person","@id":"https:\/\/www.arssenasa.gob.do\/#\/schema\/person\/b9d6c2c58f44cdecdcdaab7a6f9504c0","name":"SeNaSa","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.arssenasa.gob.do\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/3c45125f46520136bb5577344179f8312f2704a1174137df27ae1baa182b5a6e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3c45125f46520136bb5577344179f8312f2704a1174137df27ae1baa182b5a6e?s=96&d=mm&r=g","caption":"SeNaSa"},"url":"https:\/\/www.arssenasa.gob.do\/index.php\/blog\/author\/admin\/"},false]}},"yasr_visitor_votes":{"stars_attributes":{"read_only":false,"span_bottom":false},"number_of_votes":0,"sum_votes":0},"_links":{"self":[{"href":"https:\/\/www.arssenasa.gob.do\/index.php\/wp-json\/wp\/v2\/posts\/1630","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.arssenasa.gob.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.arssenasa.gob.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.arssenasa.gob.do\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.arssenasa.gob.do\/index.php\/wp-json\/wp\/v2\/comments?post=1630"}],"version-history":[{"count":0,"href":"https:\/\/www.arssenasa.gob.do\/index.php\/wp-json\/wp\/v2\/posts\/1630\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.arssenasa.gob.do\/index.php\/wp-json\/wp\/v2\/media\/1631"}],"wp:attachment":[{"href":"https:\/\/www.arssenasa.gob.do\/index.php\/wp-json\/wp\/v2\/media?parent=1630"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.arssenasa.gob.do\/index.php\/wp-json\/wp\/v2\/categories?post=1630"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.arssenasa.gob.do\/index.php\/wp-json\/wp\/v2\/tags?post=1630"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}