{"id":1633,"date":"2019-02-07T10:33:20","date_gmt":"2019-02-07T14:33:20","guid":{"rendered":"http:\/\/192.168.1.138\/wordpress\/?p=1633"},"modified":"2022-07-22T08:32:00","modified_gmt":"2022-07-22T12:32:00","slug":"senasa-firma-acuerdo-con-ministerio-de-salud-para-garantizar-a-los-afiliados-continuidad-de-tratamiento-de-alto-costo","status":"publish","type":"post","link":"https:\/\/www.arssenasa.gob.do\/index.php\/blog\/2019\/02\/07\/senasa-firma-acuerdo-con-ministerio-de-salud-para-garantizar-a-los-afiliados-continuidad-de-tratamiento-de-alto-costo\/","title":{"rendered":"SeNaSa firma acuerdo con Ministerio de Salud para garantizar a los afiliados continuidad de tratamiento de Alto Costo"},"content":{"rendered":"\n<p><strong>Santo Domingo. &#8211;<\/strong>El Seguro Nacional de Salud (SeNaSa) y el Ministerio de Salud P\u00fablica (MSP) firmaron un acuerdo para garantizar a los afiliados los medicamentos de Alto Costo, que en una primera fase ser\u00e1 para tratamientos oncol\u00f3gicos y trasplante incluidos en el Plan de Servicios de Salud (PDSS 3.0), para evitar que el afiliado interrumpa su proceso.<\/p>\n\n\n\n<p>El acuerdo en conjunto abarca los afiliados de los diferentes reg\u00edmenes y planes que maneja la ARS del Estado, con el cual se logra optimizar la cobertura y reducir los tiempos de entrega de medicamentos para los tratamientos de oncolog\u00eda y trasplante.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignright is-resized\"><img fetchpriority=\"high\" decoding=\"async\" src=\"http:\/\/192.168.1.138\/wordpress\/wp-content\/uploads\/2019\/02\/Foto-02.jpg\" alt=\"\" class=\"wp-image-1635\" width=\"386\" height=\"554\" srcset=\"https:\/\/www.arssenasa.gob.do\/wp-content\/uploads\/2019\/02\/Foto-02.jpg 585w, https:\/\/www.arssenasa.gob.do\/wp-content\/uploads\/2019\/02\/Foto-02-209x300.jpg 209w\" sizes=\"(max-width: 386px) 100vw, 386px\" \/><figcaption> Doctora Mercedes Rodr\u00edguez Silver, directora ejecutiva de SeNaSa. <\/figcaption><\/figure><\/div>\n\n\n\n<p>Durante la firma del convenio, la directora ejecutiva de SeNaSa, la doctora Mercedes Rodr\u00edguez Silver, explic\u00f3 que \u201ccon este acuerdo vamos a garantizar que con la entrega oportuna de los medicamentos de Alto Costo los afiliados no tengan que detener el tratamiento, impactando directamente en su calidad de vida\u201d<\/p>\n\n\n\n<p>Tambi\u00e9n, agreg\u00f3 que \u201cDesde SeNaSa se trabaja para garantizar a los afiliados lo que por derecho le corresponde, un acceso digno y oportuno a los servicios de salud\u201d.<\/p>\n\n\n\n<p>\u201cCon la firma de este documento continuamos fortaleciendo la cobertura y acceso a la salud de la poblaci\u00f3n: Este aporte de SeNaSa es de gran importancia para la sostenibilidad y consistencia del Programa de Medicamentos de Alto Costo, que contribuye a que los segmentos econ\u00f3micamente m\u00e1s vulnerables tengan mayor acceso a los f\u00e1rmacos para tratar padecimientos que conllevan a la familia un costo elevado\u201d indic\u00f3 el Ministro de Salud P\u00fablica, Rafael S\u00e1nchez C\u00e1rdenas.<\/p>\n\n\n\n<p>Como parte del convenio ambas instituciones acuerdan fortalecer las acciones de promoci\u00f3n de la salud y detecci\u00f3n de condiciones de Alto Costo en el Primer Nivel Atenci\u00f3n y servicios especializados, as\u00ed como el desarrollo de programas de cuidados paliativos orientados a la reducci\u00f3n del gasto en tratamiento, apoyo a los pacientes y sus familiares.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" width=\"940\" height=\"627\" src=\"http:\/\/192.168.1.138\/wordpress\/wp-content\/uploads\/2019\/02\/Foto-03.jpg\" alt=\"\" class=\"wp-image-1636\" srcset=\"https:\/\/www.arssenasa.gob.do\/wp-content\/uploads\/2019\/02\/Foto-03.jpg 940w, https:\/\/www.arssenasa.gob.do\/wp-content\/uploads\/2019\/02\/Foto-03-300x200.jpg 300w, https:\/\/www.arssenasa.gob.do\/wp-content\/uploads\/2019\/02\/Foto-03-768x512.jpg 768w\" sizes=\"(max-width: 940px) 100vw, 940px\" \/><figcaption> Rafael S\u00e1nchez C\u00e1rdenas, Ministro de Salud P\u00fablica. <\/figcaption><\/figure>\n\n\n\n<p><strong>Acto de firma<\/strong><\/p>\n\n\n\n<p>El convenio fue firmado en la Sede del Ministerio de Salud P\u00fablica por la doctora Mercedes Rodr\u00edguez Silver, directora ejecutiva de SeNaSa y por el Ministro de Salud, Rafael S\u00e1nchez C\u00e1rdenas.<\/p>\n\n\n\n<p>A trav\u00e9s de este acuerdo, tambi\u00e9n se estar\u00e1n optimizando los recursos que se destinan a coberturas de tratamientos oncol\u00f3gicos y trasplante al unir esfuerzo con el Ministerio de Salud P\u00fablica para una oportuna disponibilidad de los medicamentos.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" width=\"1024\" height=\"621\" src=\"http:\/\/192.168.1.138\/wordpress\/wp-content\/uploads\/2019\/02\/Foto-01-1-1024x621.jpg\" alt=\"\" class=\"wp-image-1637\" srcset=\"https:\/\/www.arssenasa.gob.do\/wp-content\/uploads\/2019\/02\/Foto-01-1-1024x621.jpg 1024w, https:\/\/www.arssenasa.gob.do\/wp-content\/uploads\/2019\/02\/Foto-01-1-300x182.jpg 300w, https:\/\/www.arssenasa.gob.do\/wp-content\/uploads\/2019\/02\/Foto-01-1-768x466.jpg 768w, https:\/\/www.arssenasa.gob.do\/wp-content\/uploads\/2019\/02\/Foto-01-1.jpg 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption> Doctora Mercedes Rodr\u00edguez Silver, directora ejecutiva de SeNaSa y Rafael S\u00e1nchez C\u00e1rdenas, Ministro de Salud P\u00fablica durante la firma del acuerdo para garantizar a los afiliados continuidad de tratamiento de Alto Costo. <\/figcaption><\/figure>\n\n\n\n<p style=\"text-align:right\"><strong>Gerencia de Comunicaci\u00f3n Estrat\u00e9gica. Mi\u00e9rcoles 06 de febrero de 2019.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Santo Domingo. &#8211;El Seguro Nacional de Salud (SeNaSa) y el Ministerio de Salud P\u00fablica (MSP) firmaron un acuerdo para garantizar a los afiliados los medicamentos de Alto Costo, que en una primera fase ser\u00e1 para tratamientos oncol\u00f3gicos y trasplante incluidos en el Plan de Servicios de Salud (PDSS 3.0), para evitar que el afiliado interrumpa [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":1634,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"yasr_overall_rating":0,"yasr_post_is_review":"","yasr_auto_insert_disabled":"","yasr_review_type":"","_glsr_average":0,"_glsr_ranking":0,"_glsr_reviews":0,"footnotes":""},"categories":[48,13,22],"tags":[],"class_list":["post-1633","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-acuerdos","category-noticias","category-rs"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>SeNaSa firma acuerdo con Ministerio de Salud para garantizar a los afiliados continuidad de tratamiento de Alto Costo - ARSSeNaSa<\/title>\n<meta name=\"description\" content=\"%\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.arssenasa.gob.do\/index.php\/blog\/2019\/02\/07\/senasa-firma-acuerdo-con-ministerio-de-salud-para-garantizar-a-los-afiliados-continuidad-de-tratamiento-de-alto-costo\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"SeNaSa firma acuerdo con Ministerio de Salud para garantizar a los afiliados continuidad de tratamiento de Alto Costo - ARSSeNaSa\" \/>\n<meta property=\"og:description\" content=\"%\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.arssenasa.gob.do\/index.php\/blog\/2019\/02\/07\/senasa-firma-acuerdo-con-ministerio-de-salud-para-garantizar-a-los-afiliados-continuidad-de-tratamiento-de-alto-costo\/\" \/>\n<meta property=\"og:site_name\" content=\"ARSSeNaSa\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ARSSeNaSaRD\" \/>\n<meta property=\"article:published_time\" content=\"2019-02-07T14:33:20+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-07-22T12:32:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.arssenasa.gob.do\/wp-content\/uploads\/2019\/02\/Foto-01.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"776\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"SeNaSa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@arssenasard\" \/>\n<meta name=\"twitter:site\" content=\"@arssenasard\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"SeNaSa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.arssenasa.gob.do\/index.php\/blog\/2019\/02\/07\/senasa-firma-acuerdo-con-ministerio-de-salud-para-garantizar-a-los-afiliados-continuidad-de-tratamiento-de-alto-costo\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.arssenasa.gob.do\/index.php\/blog\/2019\/02\/07\/senasa-firma-acuerdo-con-ministerio-de-salud-para-garantizar-a-los-afiliados-continuidad-de-tratamiento-de-alto-costo\/\"},\"author\":{\"name\":\"SeNaSa\",\"@id\":\"https:\/\/www.arssenasa.gob.do\/#\/schema\/person\/b9d6c2c58f44cdecdcdaab7a6f9504c0\"},\"headline\":\"SeNaSa firma acuerdo con Ministerio de Salud para garantizar a los afiliados continuidad de tratamiento de Alto Costo\",\"datePublished\":\"2019-02-07T14:33:20+00:00\",\"dateModified\":\"2022-07-22T12:32:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.arssenasa.gob.do\/index.php\/blog\/2019\/02\/07\/senasa-firma-acuerdo-con-ministerio-de-salud-para-garantizar-a-los-afiliados-continuidad-de-tratamiento-de-alto-costo\/\"},\"wordCount\":483,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.arssenasa.gob.do\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.arssenasa.gob.do\/index.php\/blog\/2019\/02\/07\/senasa-firma-acuerdo-con-ministerio-de-salud-para-garantizar-a-los-afiliados-continuidad-de-tratamiento-de-alto-costo\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.arssenasa.gob.do\/wp-content\/uploads\/2019\/02\/Foto-01.jpg\",\"articleSection\":[\"Acuerdos\",\"Noticias\",\"R\u00e9gimen Subsidiado\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.arssenasa.gob.do\/index.php\/blog\/2019\/02\/07\/senasa-firma-acuerdo-con-ministerio-de-salud-para-garantizar-a-los-afiliados-continuidad-de-tratamiento-de-alto-costo\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.arssenasa.gob.do\/index.php\/blog\/2019\/02\/07\/senasa-firma-acuerdo-con-ministerio-de-salud-para-garantizar-a-los-afiliados-continuidad-de-tratamiento-de-alto-costo\/\",\"url\":\"https:\/\/www.arssenasa.gob.do\/index.php\/blog\/2019\/02\/07\/senasa-firma-acuerdo-con-ministerio-de-salud-para-garantizar-a-los-afiliados-continuidad-de-tratamiento-de-alto-costo\/\",\"name\":\"SeNaSa firma acuerdo con Ministerio de Salud para garantizar a los afiliados continuidad de tratamiento de Alto Costo - ARSSeNaSa\",\"isPartOf\":{\"@id\":\"https:\/\/www.arssenasa.gob.do\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.arssenasa.gob.do\/index.php\/blog\/2019\/02\/07\/senasa-firma-acuerdo-con-ministerio-de-salud-para-garantizar-a-los-afiliados-continuidad-de-tratamiento-de-alto-costo\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.arssenasa.gob.do\/index.php\/blog\/2019\/02\/07\/senasa-firma-acuerdo-con-ministerio-de-salud-para-garantizar-a-los-afiliados-continuidad-de-tratamiento-de-alto-costo\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.arssenasa.gob.do\/wp-content\/uploads\/2019\/02\/Foto-01.jpg\",\"datePublished\":\"2019-02-07T14:33:20+00:00\",\"dateModified\":\"2022-07-22T12:32:00+00:00\",\"description\":\"%\",\"breadcrumb\":{\"@id\":\"https:\/\/www.arssenasa.gob.do\/index.php\/blog\/2019\/02\/07\/senasa-firma-acuerdo-con-ministerio-de-salud-para-garantizar-a-los-afiliados-continuidad-de-tratamiento-de-alto-costo\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.arssenasa.gob.do\/index.php\/blog\/2019\/02\/07\/senasa-firma-acuerdo-con-ministerio-de-salud-para-garantizar-a-los-afiliados-continuidad-de-tratamiento-de-alto-costo\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.arssenasa.gob.do\/index.php\/blog\/2019\/02\/07\/senasa-firma-acuerdo-con-ministerio-de-salud-para-garantizar-a-los-afiliados-continuidad-de-tratamiento-de-alto-costo\/#primaryimage\",\"url\":\"https:\/\/www.arssenasa.gob.do\/wp-content\/uploads\/2019\/02\/Foto-01.jpg\",\"contentUrl\":\"https:\/\/www.arssenasa.gob.do\/wp-content\/uploads\/2019\/02\/Foto-01.jpg\",\"width\":1280,\"height\":776},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.arssenasa.gob.do\/index.php\/blog\/2019\/02\/07\/senasa-firma-acuerdo-con-ministerio-de-salud-para-garantizar-a-los-afiliados-continuidad-de-tratamiento-de-alto-costo\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\/\/www.arssenasa.gob.do\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"SeNaSa firma acuerdo con Ministerio de Salud para garantizar a los afiliados continuidad de tratamiento de Alto Costo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.arssenasa.gob.do\/#website\",\"url\":\"https:\/\/www.arssenasa.gob.do\/\",\"name\":\"ARSSeNaSa\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.arssenasa.gob.do\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.arssenasa.gob.do\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.arssenasa.gob.do\/#organization\",\"name\":\"SeNaSa - Seguro Nacional de Salud\",\"url\":\"https:\/\/www.arssenasa.gob.do\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.arssenasa.gob.do\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.arssenasa.gob.do\/wp-content\/uploads\/2018\/11\/logo2022.png\",\"contentUrl\":\"https:\/\/www.arssenasa.gob.do\/wp-content\/uploads\/2018\/11\/logo2022.png\",\"width\":310,\"height\":200,\"caption\":\"SeNaSa - Seguro Nacional de Salud\"},\"image\":{\"@id\":\"https:\/\/www.arssenasa.gob.do\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/ARSSeNaSaRD\",\"https:\/\/x.com\/arssenasard\",\"https:\/\/www.instagram.com\/arssenasard\/\",\"https:\/\/www.youtube.com\/user\/ARSSeNaSa\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.arssenasa.gob.do\/#\/schema\/person\/b9d6c2c58f44cdecdcdaab7a6f9504c0\",\"name\":\"SeNaSa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.arssenasa.gob.do\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/3c45125f46520136bb5577344179f8312f2704a1174137df27ae1baa182b5a6e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/3c45125f46520136bb5577344179f8312f2704a1174137df27ae1baa182b5a6e?s=96&d=mm&r=g\",\"caption\":\"SeNaSa\"},\"url\":\"https:\/\/www.arssenasa.gob.do\/index.php\/blog\/author\/admin\/\"},false]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"SeNaSa firma acuerdo con Ministerio de Salud para garantizar a los afiliados continuidad de tratamiento de Alto Costo - ARSSeNaSa","description":"%","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.arssenasa.gob.do\/index.php\/blog\/2019\/02\/07\/senasa-firma-acuerdo-con-ministerio-de-salud-para-garantizar-a-los-afiliados-continuidad-de-tratamiento-de-alto-costo\/","og_locale":"es_ES","og_type":"article","og_title":"SeNaSa firma acuerdo con Ministerio de Salud para garantizar a los afiliados continuidad de tratamiento de Alto Costo - ARSSeNaSa","og_description":"%","og_url":"https:\/\/www.arssenasa.gob.do\/index.php\/blog\/2019\/02\/07\/senasa-firma-acuerdo-con-ministerio-de-salud-para-garantizar-a-los-afiliados-continuidad-de-tratamiento-de-alto-costo\/","og_site_name":"ARSSeNaSa","article_publisher":"https:\/\/www.facebook.com\/ARSSeNaSaRD","article_published_time":"2019-02-07T14:33:20+00:00","article_modified_time":"2022-07-22T12:32:00+00:00","og_image":[{"width":1280,"height":776,"url":"https:\/\/www.arssenasa.gob.do\/wp-content\/uploads\/2019\/02\/Foto-01.jpg","type":"image\/jpeg"}],"author":"SeNaSa","twitter_card":"summary_large_image","twitter_creator":"@arssenasard","twitter_site":"@arssenasard","twitter_misc":{"Written by":"SeNaSa","Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.arssenasa.gob.do\/index.php\/blog\/2019\/02\/07\/senasa-firma-acuerdo-con-ministerio-de-salud-para-garantizar-a-los-afiliados-continuidad-de-tratamiento-de-alto-costo\/#article","isPartOf":{"@id":"https:\/\/www.arssenasa.gob.do\/index.php\/blog\/2019\/02\/07\/senasa-firma-acuerdo-con-ministerio-de-salud-para-garantizar-a-los-afiliados-continuidad-de-tratamiento-de-alto-costo\/"},"author":{"name":"SeNaSa","@id":"https:\/\/www.arssenasa.gob.do\/#\/schema\/person\/b9d6c2c58f44cdecdcdaab7a6f9504c0"},"headline":"SeNaSa firma acuerdo con Ministerio de Salud para garantizar a los afiliados continuidad de tratamiento de Alto Costo","datePublished":"2019-02-07T14:33:20+00:00","dateModified":"2022-07-22T12:32:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.arssenasa.gob.do\/index.php\/blog\/2019\/02\/07\/senasa-firma-acuerdo-con-ministerio-de-salud-para-garantizar-a-los-afiliados-continuidad-de-tratamiento-de-alto-costo\/"},"wordCount":483,"commentCount":0,"publisher":{"@id":"https:\/\/www.arssenasa.gob.do\/#organization"},"image":{"@id":"https:\/\/www.arssenasa.gob.do\/index.php\/blog\/2019\/02\/07\/senasa-firma-acuerdo-con-ministerio-de-salud-para-garantizar-a-los-afiliados-continuidad-de-tratamiento-de-alto-costo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.arssenasa.gob.do\/wp-content\/uploads\/2019\/02\/Foto-01.jpg","articleSection":["Acuerdos","Noticias","R\u00e9gimen Subsidiado"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.arssenasa.gob.do\/index.php\/blog\/2019\/02\/07\/senasa-firma-acuerdo-con-ministerio-de-salud-para-garantizar-a-los-afiliados-continuidad-de-tratamiento-de-alto-costo\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.arssenasa.gob.do\/index.php\/blog\/2019\/02\/07\/senasa-firma-acuerdo-con-ministerio-de-salud-para-garantizar-a-los-afiliados-continuidad-de-tratamiento-de-alto-costo\/","url":"https:\/\/www.arssenasa.gob.do\/index.php\/blog\/2019\/02\/07\/senasa-firma-acuerdo-con-ministerio-de-salud-para-garantizar-a-los-afiliados-continuidad-de-tratamiento-de-alto-costo\/","name":"SeNaSa firma acuerdo con Ministerio de Salud para garantizar a los afiliados continuidad de tratamiento de Alto Costo - ARSSeNaSa","isPartOf":{"@id":"https:\/\/www.arssenasa.gob.do\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.arssenasa.gob.do\/index.php\/blog\/2019\/02\/07\/senasa-firma-acuerdo-con-ministerio-de-salud-para-garantizar-a-los-afiliados-continuidad-de-tratamiento-de-alto-costo\/#primaryimage"},"image":{"@id":"https:\/\/www.arssenasa.gob.do\/index.php\/blog\/2019\/02\/07\/senasa-firma-acuerdo-con-ministerio-de-salud-para-garantizar-a-los-afiliados-continuidad-de-tratamiento-de-alto-costo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.arssenasa.gob.do\/wp-content\/uploads\/2019\/02\/Foto-01.jpg","datePublished":"2019-02-07T14:33:20+00:00","dateModified":"2022-07-22T12:32:00+00:00","description":"%","breadcrumb":{"@id":"https:\/\/www.arssenasa.gob.do\/index.php\/blog\/2019\/02\/07\/senasa-firma-acuerdo-con-ministerio-de-salud-para-garantizar-a-los-afiliados-continuidad-de-tratamiento-de-alto-costo\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.arssenasa.gob.do\/index.php\/blog\/2019\/02\/07\/senasa-firma-acuerdo-con-ministerio-de-salud-para-garantizar-a-los-afiliados-continuidad-de-tratamiento-de-alto-costo\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.arssenasa.gob.do\/index.php\/blog\/2019\/02\/07\/senasa-firma-acuerdo-con-ministerio-de-salud-para-garantizar-a-los-afiliados-continuidad-de-tratamiento-de-alto-costo\/#primaryimage","url":"https:\/\/www.arssenasa.gob.do\/wp-content\/uploads\/2019\/02\/Foto-01.jpg","contentUrl":"https:\/\/www.arssenasa.gob.do\/wp-content\/uploads\/2019\/02\/Foto-01.jpg","width":1280,"height":776},{"@type":"BreadcrumbList","@id":"https:\/\/www.arssenasa.gob.do\/index.php\/blog\/2019\/02\/07\/senasa-firma-acuerdo-con-ministerio-de-salud-para-garantizar-a-los-afiliados-continuidad-de-tratamiento-de-alto-costo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.arssenasa.gob.do\/"},{"@type":"ListItem","position":2,"name":"SeNaSa firma acuerdo con Ministerio de Salud para garantizar a los afiliados continuidad de tratamiento de Alto Costo"}]},{"@type":"WebSite","@id":"https:\/\/www.arssenasa.gob.do\/#website","url":"https:\/\/www.arssenasa.gob.do\/","name":"ARSSeNaSa","description":"","publisher":{"@id":"https:\/\/www.arssenasa.gob.do\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.arssenasa.gob.do\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.arssenasa.gob.do\/#organization","name":"SeNaSa - Seguro Nacional de Salud","url":"https:\/\/www.arssenasa.gob.do\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.arssenasa.gob.do\/#\/schema\/logo\/image\/","url":"https:\/\/www.arssenasa.gob.do\/wp-content\/uploads\/2018\/11\/logo2022.png","contentUrl":"https:\/\/www.arssenasa.gob.do\/wp-content\/uploads\/2018\/11\/logo2022.png","width":310,"height":200,"caption":"SeNaSa - Seguro Nacional de Salud"},"image":{"@id":"https:\/\/www.arssenasa.gob.do\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ARSSeNaSaRD","https:\/\/x.com\/arssenasard","https:\/\/www.instagram.com\/arssenasard\/","https:\/\/www.youtube.com\/user\/ARSSeNaSa"]},{"@type":"Person","@id":"https:\/\/www.arssenasa.gob.do\/#\/schema\/person\/b9d6c2c58f44cdecdcdaab7a6f9504c0","name":"SeNaSa","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.arssenasa.gob.do\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/3c45125f46520136bb5577344179f8312f2704a1174137df27ae1baa182b5a6e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3c45125f46520136bb5577344179f8312f2704a1174137df27ae1baa182b5a6e?s=96&d=mm&r=g","caption":"SeNaSa"},"url":"https:\/\/www.arssenasa.gob.do\/index.php\/blog\/author\/admin\/"},false]}},"yasr_visitor_votes":{"stars_attributes":{"read_only":false,"span_bottom":false},"number_of_votes":0,"sum_votes":0},"_links":{"self":[{"href":"https:\/\/www.arssenasa.gob.do\/index.php\/wp-json\/wp\/v2\/posts\/1633","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.arssenasa.gob.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.arssenasa.gob.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.arssenasa.gob.do\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.arssenasa.gob.do\/index.php\/wp-json\/wp\/v2\/comments?post=1633"}],"version-history":[{"count":1,"href":"https:\/\/www.arssenasa.gob.do\/index.php\/wp-json\/wp\/v2\/posts\/1633\/revisions"}],"predecessor-version":[{"id":2880,"href":"https:\/\/www.arssenasa.gob.do\/index.php\/wp-json\/wp\/v2\/posts\/1633\/revisions\/2880"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.arssenasa.gob.do\/index.php\/wp-json\/wp\/v2\/media\/1634"}],"wp:attachment":[{"href":"https:\/\/www.arssenasa.gob.do\/index.php\/wp-json\/wp\/v2\/media?parent=1633"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.arssenasa.gob.do\/index.php\/wp-json\/wp\/v2\/categories?post=1633"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.arssenasa.gob.do\/index.php\/wp-json\/wp\/v2\/tags?post=1633"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}